{"id":1000,"date":"2011-03-23T17:40:53","date_gmt":"2011-03-23T15:40:53","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1000"},"modified":"2011-03-23T17:40:53","modified_gmt":"2011-03-23T15:40:53","slug":"jordan-y-su-mision-salvatoriana","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/jordan-y-su-mision-salvatoriana\/","title":{"rendered":"Jord\u00e1n y su misi\u00f3n Salvatoriana"},"content":{"rendered":"<p>Los salvatorianos estamos contentos, y agradecidos a Dios y a Nuestra Madre Mar\u00eda, por las virtudes de nuestro Fundador y sus deseos de anunciar el Reino de Dios, la Buena noticia a todos los pueblos, con todos los medios que la Caridad de Cristo nos inspira, siendo capaces de popularizar las verdades eternas, desde la formaci\u00f3n de Cristianos adultos. Gran misi\u00f3n, y un gran reto que tenemos.<br \/>\nSer\u00e1 posible si seguimos su vida de Oraci\u00f3n, de confianza en la Divina providencia, de entrega, de fraternidad, de unidad en el amor, de solidaridad y cercan\u00eda con los m\u00e1s desfavorecidos y necesitados..<br \/>\nUn abrazo Chema sds,<\/p>\n<p>Jordan Francesco Maria della Croce Venerabile<\/p>\n<p>Solemnidad de San Jos\u00e9<\/p>\n<p><strong>Homil\u00eda <\/p>\n<p>Angelo Card. Amato, SDB<\/p>\n<p><\/strong><br \/>\n1. Me uno a vuestra alegr\u00eda por el decreto sobre las virtudes heroicas del Siervo de Dios, Francisco Mar\u00eda de la Cruz Jord\u00e1n (1848-1818). Podemos hacer nuestras las palabras de alegr\u00eda del salmista: \u00abCantar\u00e9 eternamente el amor del Se\u00f1or, de generaci\u00f3n en generaci\u00f3n har\u00e9 conocer con mi boca tu fidelidad\u00bb (Sal 89,2).<br \/>\nNuestro agradecimiento a Dios Trinidad, fuente y dador de todo bien, y hoy en el d\u00eda de su santo, tambi\u00e9n al Santo Padre Benedicto XVI quien el pasado 14 de Enero ha autorizado la promulgaci\u00f3n. Con evidente satisfacci\u00f3n, el Papa ha reconocido la heroicidad de las virtudes cristianas de un hijo tan ilustre y benem\u00e9rito de la Iglesia alemana y de la Iglesia universal. La Iglesia, por lo tanto, declara que la santidad es la fuente de las muchas obras realizadas por el Padre Jord\u00e1n, de cuyo coraz\u00f3n bueno y generoso nace la fundaci\u00f3n de la \u201cSociedad del Divino Salvador\u201d y de la Congregaci\u00f3n de las Hermanas del Divino Salvador\u201d. Su existencia virtuosa es la que hace germinar su acci\u00f3n apost\u00f3lica y misionera, as\u00ed como la savia del \u00e1rbol da alimento y vigor a las flores que se abren en primavera y madura los frutos en verano. El Venerable Padre Jord\u00e1n se elev\u00f3 por encima de nuestra mediocridad mediante su fe profunda, su gran esperanza y su generosa caridad.<br \/>\n2. La solemnidad de San Jos\u00e9, nos da hoy la ocasi\u00f3n propicia para meditar especialmente sobre la virtud de la fe. Como el patriarca Abrah\u00e1n, nuestro padre en la fe, como Mar\u00eda, nuestra madre en la fe, tambi\u00e9n San Jos\u00e9 fue un hombre probado en la fe. Por la fe acogi\u00f3 a la joven esposa, gr\u00e1vida de Jes\u00fas: \u00abJos\u00e9, hijo de David, no temas tomar contigo a Mar\u00eda tu mujer porque lo engendrado en ella, es del Esp\u00edritu Santo\u00bb [\u2026] Despertado Jos\u00e9 del sue\u00f1o, hizo como el \u00e1ngel del Se\u00f1or le hab\u00eda mandado\u00bb (Mateo 1,20.24). Por la fe contempl\u00f3 el nacimiento milagroso del Hijo del Padre celestial en la pobreza de Bel\u00e9n. Por la fe anduvo exiliado y pobre en Egipto con Mar\u00eda y con el ni\u00f1o Jes\u00fas. Por la fe acogi\u00f3, sin contradecir, las palabras de Jes\u00fas de doce a\u00f1os, al encontrarlo en el templo. Por la fe Jos\u00e9 viaj\u00f3 por caminos obscuros y para \u00e9l incomprensibles, s\u00f3lo esclarecidos por la luz de la divina providencia. No vacil\u00f3: \u00abCrey\u00f3, esperando contra toda esperanza\u00bb (Romanos 4,18). Su santidad no est\u00e1 fundada en palabras sino en el ser y en el actuar. Por eso Jos\u00e9 es llamado en el Evangelio hombre \u201cjusto\u201d (Mateo 1,19). Conservamos algunas palabras de Mar\u00eda, pero de Jos\u00e9, ni una sola. \u00c9l es el hombre del silencio, de la meditaci\u00f3n y de la obediencia inmediata a la voluntad de Dios, por medio de los hechos. <\/p>\n<p>3. Hay una coincidencia providencial de situaciones entre san Jos\u00e9 y el Venerable  Francisco Mar\u00eda de la Cruz Jord\u00e1n. El joven Juan Bautista Jord\u00e1n  (nombre de bautismo del Venerable) fue hasta la edad de veinte a\u00f1os un obrero, como el gran patriarca b\u00edblico. Despu\u00e9s de la escuela primaria, trabaj\u00f3 como obrero ocasional y como pintor de brocha gorda, hasta que, despu\u00e9s de los veinte a\u00f1os, decidi\u00f3 obedecer a la voz del Se\u00f1or, que lo llamaba a su servicio como sacerdote. Empez\u00f3 para \u00e9l un periodo de preparaci\u00f3n intensa no solo en las ciencias sagradas sino tambi\u00e9n en las lenguas modernas y antiguas. Debido al clima cultural de su tiempo, que corr\u00eda el riesgo de una verdadera apostas\u00eda del Evangelio y de la Iglesia, se dio cuenta que se necesitaba una misi\u00f3n entendida no s\u00f3lo de manera tradicional como \u201cmissio ad gentes\u201d, es decir como proclamaci\u00f3n del Evangelio a todos los pueblos del mundo, especialmente a los m\u00e1s apartados, sino tambi\u00e9n de manera moderna, como un fortalecimiento de la identidad cat\u00f3lica de los fieles de su patria, mediante una motivaci\u00f3n cultural m\u00e1s fuerte sobre las razones de la propia fe. \u00c9l es un ap\u00f3stol de la primera evangelizaci\u00f3n, para conducir a toda la humanidad a Cristo, y de la nueva evangelizaci\u00f3n, para encender de nuevo la fe de los creyentes, a veces d\u00e9bil y cansada. La ideolog\u00eda anticat\u00f3lica del Kulturkampf y el abandono de la fe por parte de no pocos bautizados, refuerzan en su mente una santa inquietud apost\u00f3lica. Ya como seminarista hab\u00eda hecho suyas las palabras del Benedictus: \u00ab\u2026 iluminar a los que habitan en tinieblas y sombras de muerte \u00bb (Lucas 1,79). Siendo joven sacerdote le impact\u00f3 una frase del Evangelio de San Juan: \u00abEsta es la vida eterna: que te conozcan a ti, el \u00fanico Dios verdadero, y al que t\u00fa has enviado, Jesucristo\u00bb (Juan 17,3).<br \/>\nSe propag\u00f3 entonces su celo apost\u00f3lico al realizar la fundaci\u00f3n de dos congregaciones misioneras: la \u201cSociedad del Divino Salvador\u201d y la \u201cCongregaci\u00f3n de las Hermanas del Divino Salvador\u201d.  Un d\u00eda anot\u00f3 en su Diario Espiritual las palabras de San Francisco Javier: \u00ab Mientras haya un rinc\u00f3n en el mundo, donde no se ame a Dios, yo no podr\u00e9 permitirme un momento de descanso\u00bb.  Y unos a\u00f1os m\u00e1s adelante hizo este prop\u00f3sito: \u00ab\u00a1S\u00e9 un aut\u00e9ntico ap\u00f3stol de Jesucristo y no descanses hasta que hayas llevado la palabra del Se\u00f1or a todos los extremos de la tierra; S\u00e9 un verdadero pregonero del Alt\u00edsimo! \u00a1Vuela por la tierra como un \u00e1guila y predica la palabra de Dios!\u00bb.<br \/>\nCuando su Sociedad tuvo una moderada expansi\u00f3n con muchas vocaciones, escribi\u00f3 una vez m\u00e1s: \u00abMientras Dios no sea glorificado en todas partes, no puedes permitirte un solo instante de reposo. Mientras no sea alabada en todas partes la Reina del cielo y de la tierra no puedes descansar ni un solo momento. Ning\u00fan sacrificio, ninguna cruz, ning\u00fan sufrimiento, ninguna desolaci\u00f3n, ninguna tribulaci\u00f3n, ning\u00fan ataque. Oh, nada te sea demasiado dif\u00edcil con la gracia de Dios [\u2026]. Todo lo puedo en Aquel que me fortalece\u00bb .<br \/>\nEstaba completamente devorado por la pasi\u00f3n misionera de anunciar a Cristo al mundo. Un d\u00eda anot\u00f3 en lat\u00edn: \u00abOmnes, omnes, o Jesu, omnes, o Salvator Mundi, salvare desidero vehementissime!\u00bb. [Todos, todos, oh Jes\u00fas, todos, oh Salvador del Mundo, los deseo salvar con mucha vehemencia!] \u00abOmnes Populi, omnes Gentes, omnes Tribus, omnes Nationes, omnes Linguae, laudate nomen Domini!\u00bb.  [Todos los pueblos, todas las gentes, todas las tribus, todas las naciones, todas las lenguas, alabad el nombre del Se\u00f1or!]<\/p>\n<p>4. La inquietud apost\u00f3lica de este hombre justo proven\u00eda de su gran fe en la presencia de Cristo Salvador y en la misi\u00f3n salvadora de la Iglesia que le empujaba a manifestar su entusiasmo incontenible. La monumental Positio acerca de su vida y de sus virtudes se detiene largamente sobre su esp\u00edritu de fe, que se manifestaba no s\u00f3lo en su ardiente celo apost\u00f3lico, sino tambi\u00e9n en una devoci\u00f3n eucar\u00edstica hecha de oraci\u00f3n y de adoraci\u00f3n. De su gran esp\u00edritu de fe se originaba tambi\u00e9n su inquebrantable confianza en la Divina Providencia. S\u00f3lo quien tiene confianza en ella, puede colaborar plenamente con Dios y con su Reino. Los testigos concuerdan al afirmar que por su inquebrantable confianza en la presencia de Dios en su vida, el Padre Jord\u00e1n pudo acudir diariamente,  en el transcurrir del tiempo a m\u00e1s de 300 personas, aunque estuviera verdaderamente desprovisto de bienes materiales.   El Padre Hubertus Kreutzer afirma: \u00abNi siquiera en la dificultades m\u00e1s grandes lo abandonaba su confianza en Dios; la fe en la Providencia y la confianza en Dios eran temas preferidos en sus alocuciones; por eso siempre llamaba la atenci\u00f3n sobre hombres de la Providencia como Don Bosco y el Cottolengo\u00bb.  Por eso usaba con frecuencia la imagen de la balanza: \u00abMi confianza en Dios y en la Providencia divina son comparables a los dos platillos de una balanza. Cuanto m\u00e1s peso se pone en uno, m\u00e1s sube el otro\u00bb.<br \/>\nCultivaba su confianza en la Divina Providencia con la oraci\u00f3n intensa ante el Sant\u00edsimo. Con mucha frecuencia estaba en adoraci\u00f3n en la capilla de la casa o en la Bas\u00edlica de San Pedro. El Padre Athanasius Kr\u00e4chan cuenta: \u00abCuando pienso en el P. Jordan, lo veo con el esp\u00edritu arrodillado ante el tabern\u00e1culo en la capilla privada de la Casa Madre o en San Pedro [\u2026]. Cuando el Siervo de Dios entraba en la capilla yo le ofrec\u00eda el agua bendita y pude observar que el P. Jord\u00e1n, al entrar en la capilla, ya hab\u00eda olvidado todo lo que le rodeaba y nada era tan importante para \u00e9l, como el tabern\u00e1culo. Su genuflexi\u00f3n era siempre una predicaci\u00f3n para nosotros. En la forma como saludaba al Sant\u00edsimo, se notaba que ya hab\u00eda establecido un contacto personal con Jesucristo\u00bb.<br \/>\nOtro testigo afirma: \u00abEl gran amor hacia el Salvador oculto en el tabern\u00e1culo era una de las caracter\u00edsticas m\u00e1s sobresalientes del P. Jord\u00e1n. Le he visto centenares de veces mantener su mirada inm\u00f3vil, como en \u00e9xtasis, hacia el tabern\u00e1culo y mucho m\u00e1s ante el Sant\u00edsimo expuesto en el ostensorio. Su veneraci\u00f3n por el Sant\u00edsimo era algo conmovedor para todos los que estaban en la Capilla. \u00bb.<br \/>\nLa fe era una virtud vivida por \u00e9l y que aconsejaba a sus hijos espirituales. En una conferencia amonestaba as\u00ed a sus cohermanos: \u00abPara nosotros es sumamente importante, como obreros apost\u00f3licos, ser muy fuertes en la fe [\u2026], vivir en la fe en nuestras acciones y visiones, en nuestro trabajos y tendencias, en nuestros sufrimientos y trabajos\u00bb.<br \/>\nDe su esp\u00edritu de fe tomaba la fuerza para sobrellevar el sufrimiento, para perdonar a sus enemigos, para olvidar las ofensas, para confirmar su obediencia al Papa y a los Obispos. Sobre esto cuenta concretamente el Padre Pablo Pabst: \u00abFue un hijo sincero y devot\u00edsimo de la Santa Iglesia  y el  \u201csentire cum Ecclesia\u201d fue para \u00e9l como una segunda naturaleza\u00bb.  Otro testigo a\u00f1ade: \u00ab\u00c9l nos recomendaba siempre el \u201cspiritus ecclesiae\u201d y la aut\u00e9ntica \u201cmens Catholica\u201d\u00bb.<br \/>\nSu actitud humilde, que lo asemeja en forma extraordinaria a San Jos\u00e9, era la s\u00edntesis de su vida virtuosa, llena de fe y de caridad. La humildad es una peque\u00f1a virtud pero que hace grandes a los hombres justos. El 9 de enero del 1880 nuestro Venerable anota en su Diario: \u00abRezar mucho, much\u00edsimo, y meditar, y no apegarse jam\u00e1s a algo terreno ni dejarse llevar jam\u00e1s por los hombres y por sus habladur\u00edas, sino seguir el consejo de unos pocos siervos de Dios piadosos, dejarte llevar s\u00f3lo por Dios y por sus santos. Desprecios \u2013 Calumnias \u2013 Hacer el rid\u00edculo y muchas cosas m\u00e1s te pasar\u00e1n -, pero s\u00e9 valiente y ag\u00e1rrate fuertemente a Dios\u00bb.<br \/>\nUn abrumador entusiasmo apost\u00f3lico y misionero en la proclamaci\u00f3n de Cristo Salvador del mundo, una inmensa fe en la Divina Providencia y un profundo esp\u00edritu de humildad son s\u00f3lo algunos de los aspectos m\u00e1s caracter\u00edsticos de la personalidad virtuosa del Venerable Padre Francisco Jord\u00e1n. Su herencia espiritual es una invitaci\u00f3n para sus hijos a la contemplaci\u00f3n, a la imitaci\u00f3n e incluso a la petici\u00f3n de intercesi\u00f3n para recibir iluminaci\u00f3n, consuelo y gracias espirituales.<br \/>\nDice el Santo Padre Benedicto XVI: \u00abLa vida de los Santos no comprende s\u00f3lo su biograf\u00eda terrena, sino tambi\u00e9n su vida y actuaci\u00f3n en Dios despu\u00e9s de la muerte. En los Santos es evidente que, quien va hacia Dios no se aleja de los hombres, sino que se hace realmente cercano a ellos\u00bb.<br \/>\nAprovechemos esta cercan\u00eda espiritual para nuestro camino de perfecci\u00f3n.<\/p>\n<p>Amen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los salvatorianos estamos contentos, y agradecidos a Dios y a Nuestra Madre Mar\u00eda, por las virtudes de nuestro Fundador y sus deseos de anunciar el Reino de Dios, la Buena noticia a todos los pueblos, con todos los medios que la Caridad de Cristo nos inspira, siendo capaces de popularizar las verdades eternas, desde la &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/jordan-y-su-mision-salvatoriana\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1000","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1000"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1000\/revisions"}],"predecessor-version":[{"id":1001,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1000\/revisions\/1001"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}