{"id":1004,"date":"2011-03-27T01:57:09","date_gmt":"2011-03-26T23:57:09","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1004"},"modified":"2011-03-27T01:57:09","modified_gmt":"2011-03-26T23:57:09","slug":"el-bien-comun-en-japon-buena-leccion","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-bien-comun-en-japon-buena-leccion\/","title":{"rendered":"El Bien com\u00fan en Jap\u00f3n  Buena lecci\u00f3n"},"content":{"rendered":"<p>Sobran las palabras. \u00bb Dar la vida por los dem\u00e1s\u00bb nos suena? No es el mensaje de Jes\u00fas lo que importa? Parece que lo importante es vivir el \u00bb evangelio\u00bb siguiendo a Jes\u00fas. Podemos creer que es as\u00ed, que asi lo est\u00e1n viviendo unas cuantas personas.<br \/>\nEl ejemplo vale m\u00e1s que mil palabras piadosas&#8230;Chema sds,<\/p>\n<p><strong>Yamato-Damashii: LA SUPREMAC\u00cdA DEL BIEN COMUN<br \/>\n<\/strong><br \/>\nEl mundo los conoce como \u201clos h\u00e9roes de Fukushima\u201d, entre ingenieros, t\u00e9cnicos especializados y bomberos son unos 300 hombres, voluntarios todos, eligieron sacrificar su vida para evitar cientos de miles de muertes por fuga masiva de radiaci\u00f3n. Hoy una semana  del terremoto y el tsunami todo indica que lo est\u00e1n logrando. Llevan siete d\u00edas trabajando sin descanso bajo una presi\u00f3n inimaginable \u00bfcomo ser\u00e1 saber que cientos de miles de vidas est\u00e1n en sus manos y adem\u00e1s trabajar a contrarreloj? \u00bfComo ser\u00e1 saberlo y adem\u00e1s estar sometido a condiciones f\u00edsicas extremas, altas temperaturas, riesgo de derrumbes, trajes que dificultan  la movilidad,  ausencia de verdadero descanso? \u00bfC\u00f3mo ser\u00e1 realizar esa tarea con la certeza que la radiaci\u00f3n les est\u00e1 matando? \u00bfQu\u00e9 fuerza les permite soportar esa presi\u00f3n con la calma de seguir y seguir, y sobreponerse a todo, y no desfallecer? \u00bfQue milagro hace posible que no se quiebren, que no huyan, que no entren en crisis de p\u00e1nico? \u00bfQue les sostiene?<br \/>\nLos japoneses tienen una hermosa respuesta, dicen que los h\u00e9roes llevan dentro el Yamato-Damashii, es decir el esp\u00edritu japon\u00e9s. El concepto alude a algo mucho m\u00e1s grande que el patriotismo,  alude a la supremac\u00eda del bien com\u00fan sobre el ego\u00edsmo individual. Es ese esp\u00edritu el que explica que no hubiera saqueos, ni disturbios,  que la polic\u00eda no tuviera como tarea controlar a la poblaci\u00f3n y pudiera dedicarse a las tareas de ayuda y b\u00fasqueda. Es ese esp\u00edritu el que hace que no se les pase por la mente hacer negocio con la desgracia del pr\u00f3jimo y por tanto no se constatan subidas de precio de los productos de primera necesidad.<br \/>\nLa del tsunami de este intenso 2011 es la tierra de los samur\u00e1is, la tierra del honor,  la del respeto a los ancestros y al pr\u00f3jimo, es el pa\u00eds que pudo levantarse de sus cenizas luego de la segunda guerra; sin embargo, para honrar realmente la grandeza de los h\u00e9roes de Fukushima y a todo el pueblo japon\u00e9s, es otra la respuesta que debemos dar cuando nos preguntamos \u00bfqu\u00e9 les sostiene?<br \/>\nDar prevalencia al bien com\u00fan sobre el ego\u00edsmo individual es sin\u00f3nimo de grandeza y la grandeza es patrimonio del esp\u00edritu humano, el de los japoneses y tambi\u00e9n el de los doscientos mil voluntarios que murieron en Chernobyll y de los bomberos que entraron a las torres gemelas. Honramos a los japoneses y tomamos su ejemplo si comprendemos que despertar del ego\u00edsmo es tarea de TODOS. En todo ser humano mora oculto un samurai, en todos hay un H\u00e9rcules que es capaz de vencer obst\u00e1culos inimaginables, un David que puede alzarse contra una central nuclear y vencerla con su honda. Ser capaz de desplegar esa fuerza heroica para el bien com\u00fan es la esencia misma del coraz\u00f3n humano. Esa fuerza no es otra que la fuerza del alma.<br \/>\nLa mayor\u00eda de nosotros jam\u00e1s dar\u00e1 la vida en un escenario dram\u00e1tico como el que hoy mantiene al mundo en vilo y sin embargo el ejemplo de los h\u00e9roes de Fukushima nos concierne.  Goliat tienen muchos rostros, la radiaci\u00f3n con todo su horror no es el m\u00e1s terrible.  Tomemos la lecci\u00f3n que Jap\u00f3n nos ofrece, veamos la enorme belleza que siempre resplandece detr\u00e1s del dolor, no nos quedemos con las sombras. Lo que el pueblo japon\u00e9s en general y los liquidadores de la central muy en particular nos recuerdan es que el peor rostro de Goliat es el ego\u00edsmo. S\u00f3lo enfoc\u00e1ndonos al bien com\u00fan podemos ascender al alma, s\u00f3lo si ascendemos ella desciende y nos infunde su belleza, su poder, su calma.<br \/>\nNo podemos seguir considerando que el alma es algo abstracto, poco probable, poco demostrable&#8230; No podemos justificarnos con razonamientos trasnochados que persisten en que lo que es invisible e intangible no puede ser objeto de nuestra reflexi\u00f3n, ni nuestra b\u00fasqueda. Tambi\u00e9n la radiaci\u00f3n del uranio y el plutonio de Fukushima es invisible y no por ello damos por nulos sus efectos. La radiaci\u00f3n del alma humana, igual que la del \u00e1tomo, se mide por sus efectos.<br \/>\nLos efectos de nombrar el alma, son poderosos. Nombr\u00e9mosla. Redefinamos nuestra identidad, nos convertimos en aquello que pensamos de nosotros. Si nuestro pensamiento concibe la grandeza, la grandeza nos concebir\u00e1 y seremos alumbrados por ella.<br \/>\nPs. Isabella Di Carlo, 19 de Marzo de 2011<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sobran las palabras. \u00bb Dar la vida por los dem\u00e1s\u00bb nos suena? No es el mensaje de Jes\u00fas lo que importa? Parece que lo importante es vivir el \u00bb evangelio\u00bb siguiendo a Jes\u00fas. Podemos creer que es as\u00ed, que asi lo est\u00e1n viviendo unas cuantas personas. El ejemplo vale m\u00e1s que mil palabras piadosas&#8230;Chema sds, &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-bien-comun-en-japon-buena-leccion\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1004","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1004"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1004\/revisions"}],"predecessor-version":[{"id":1005,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1004\/revisions\/1005"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}