{"id":1137,"date":"2011-11-05T19:57:18","date_gmt":"2011-11-05T17:57:18","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1137"},"modified":"2011-11-05T19:57:18","modified_gmt":"2011-11-05T17:57:18","slug":"la-paz-y-la-justicia-un-grito-de-toda-la-humanidad","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/la-paz-y-la-justicia-un-grito-de-toda-la-humanidad\/","title":{"rendered":"LA PAZ Y LA JUSTICIA un grito de toda la humanidad"},"content":{"rendered":"<p>Los l\u00edderes religiosos del mundo rezan por la paz en As\u00eds<br \/>\nApreciaci\u00f3n un\u00e1nime de la iniciativa propuesta por el Papa<br \/>\nAS\u00cdS, viernes 28 de octubre de 2011 (ZENIT.org).- Todos los l\u00edderes religiosos que participaron este jueves 27 de octubre en la Jornada de reflexi\u00f3n, di\u00e1logo y oraci\u00f3n por la paz y la justicia en el mundo promovida en As\u00eds, Italia, por el papa Benedicto XVI, aplaudieron la iniciativa y expresaron, en sus intervenciones, la importancia de rezar por la paz y el di\u00e1logo.<br \/>\nEl patriarca Ecum\u00e9nico de Constantinopla, Bartolom\u00e9 I, afirm\u00f3 que el di\u00e1logo debe llevar a \u201cconsiderar al otro como sujeto de relaci\u00f3n y no como objeto de indiferencia\u201d, \u201cporque es en la indiferencia donde nace el odio, es en la indiferencia donde nace el conflicto, es en la indiferencia donde nace la violencia\u201d.<br \/>\n\u201cContra estos males, s\u00f3lo el di\u00e1logo es una soluci\u00f3n posible y a largo plazo\u201d, observ\u00f3, recordando que \u201cno vivimos \u00fanicamente los unos contra los otros, o los unos al lado de los otros, sino, sobre todo, los unos junto a los otros, en un esp\u00edritu de paz, de solidaridad y de fraternidad\u201d.<br \/>\nEn el encuentro de As\u00eds, explic\u00f3, \u201cno se trata, como algunos insin\u00faan, de realizar el di\u00e1logo interreligioso o ecum\u00e9nico, desde una perspectiva sincr\u00e9tica\u201d. Al contrario, la visi\u00f3n que nosotros alabamos, en el di\u00e1logo interreligioso, tiene un sentido especial que deriva de la capacidad misma de las religiones de invertir en el campo social para promover la paz\u201d.<br \/>\n\u201cDebemos oponernos a la deformaci\u00f3n del mensaje de las religiones y de sus s\u00edmbolos por parte de los autores de violencia\u201d, indic\u00f3. \u201cLos responsables de las religiones deben hacerse cargo del proceso de restablecimiento de la paz\u201d.<br \/>\nEsta responsabilidad, se\u00f1al\u00f3, \u201cno es simplemente verbal\u201d, sino que exige \u201cque seamos fieles a nuestra fe, fieles al dise\u00f1o de Dios para el mundo, respondiendo a lo que \u00c9l quiere\u201d.<br \/>\nEl doctor Rowan Douglas Willams, arzobispo de Canterbury, cabeza de la Iglesia Anglicana, defini\u00f3 como \u201cun gran honor\u201d el poder celebrar el aniversario de la primera Jornada de Oraci\u00f3n por la Paz, promovida por el beato Juan Pablo II.<br \/>\nUna paz duradera, declar\u00f3, \u201cinicia donde nosotros vemos al pr\u00f3jimo como a nosotros mismos y por tanto comenzamos a comprender por qu\u00e9 y c\u00f3mo debemos amar al pr\u00f3jimo como a nosotros mismos\u201d.<br \/>\nLos cristianos, especific\u00f3, reconocen en el pr\u00f3jimo \u201cno s\u00f3lo a alguien que tiene en s\u00ed &#8216;la imagen de Dios&#8217; en virtud de la creaci\u00f3n, sino a alguien que tiene en s\u00ed tambi\u00e9n la posibilidad de llevar la semejanza de Jesucristo en virtud de la nueva creaci\u00f3n\u201d.<br \/>\nSi es as\u00ed, \u201cno somo extra\u00f1os los unos de los otros. Y si no somos extra\u00f1os, debemos, antes y despu\u00e9s, encontrar el modo de concretar este reconocimiento rec\u00edproco en relaciones de amistad verdaderas y duraderas\u201d.<br \/>\n\u201cEstamos aqu\u00ed hoy para declarar nuestra voluntad \u2013de o m\u00e1s bien nuestra apasionada determinaci\u00f3n- de persuadir a nuestro mundo que los seres humanos no deben ser extra\u00f1os, y que el reconocimiento es tan posible como necesario por nuestra universal relaci\u00f3n con Dios\u201d.<br \/>\nEl doctor Olav Fykse Tveit, secretario general del Consejo Ecum\u00e9nico de las Iglesias, alab\u00f3 el encuentro de As\u00eds destacando que \u201cel mundo necesita reuniones entre los jefes de las comunidades religiosas\u201d, as\u00ed como de \u201cconstructores de paz a partir de la fe\u201d.<br \/>\nLas comunidades de fe, a su vez, \u201cnecesitan j\u00f3venes que lleven el cambio\u201d. \u201cUn gran obst\u00e1culo a una paz justa representa hoy el alto nivel de paro entre j\u00f3venes en todo el mundo\u201d, indic\u00f3. \u201cSe tiene la sensaci\u00f3n de que estamos poniendo en juego el bienestar y la felicidad de una generaci\u00f3n. Necesitamos la visi\u00f3n y la valent\u00eda de los j\u00f3venes para los cambios necesarios\u201d.<br \/>\nTveit recordando Jerusal\u00e9n, anunci\u00f3 que, para el Consejo Ecum\u00e9nico de las Iglesias, \u201cun compromiso preciso para los pr\u00f3ximos a\u00f1os ser\u00e1 el de trabajar por una paz justa en Jerusal\u00e9n\u201d y para todos los pueblos que viven en la ciudad, y en torno a ella.<br \/>\n\u201cSomos responsables ante Dios, y los unos ante los otros, de la paz de nuestro tiempo y tambi\u00e9n de lo que decimos o no decimos para alcanzarla\u201d, declar\u00f3.<br \/>\nPor su parte, el conocido rabino David Rosen, director del departamento de Asuntos Interreligiosos de la American Jewish Committee (AJC), comenz\u00f3 hablando del concepto de peregrinaci\u00f3n. \u201cUna peregrinaci\u00f3n es, por definici\u00f3n, mucho m\u00e1s que un viaje. Las palabras hebreas para peregrinaci\u00f3n son &#8216;aliyah la\u2019regel&#8217;, expresi\u00f3n que significa &#8216;subida a pie&#8217;\u201d, un concepto que ten\u00eda un significado tanto literal como espiritual: literal porque se sub\u00eda desde los montes de Judea hasta el Templo de Jerusal\u00e9n, espiritual o simb\u00f3lica en el sentido de subir hacia Dios.<br \/>\n\u201cEste concepto de peregrinaci\u00f3n, de ascenso, es central en la visi\u00f3n prof\u00e9tica del establecimiento del Reino de los Cielos en la Tierra, la visi\u00f3n mesi\u00e1nica de paz universal\u201d, a\u00f1adi\u00f3 Rosen, citando despu\u00e9s al profeta Isa\u00edas: \u201c&#8217;Vendr\u00e1n muchos pueblos y dir\u00e1n: vayamos y subamos al monte del Se\u00f1or, a la casa del Dios de Jacob, para que \u00c9l nos ense\u00f1e sus caminos y podamos caminar por sus senderos; ya que de Si\u00f3n saldr\u00e1 la ley y de Jerusal\u00e9n la Palabra del Se\u00f1or&#8217;. \u00c9l ser\u00e1 juez entre las naciones y \u00e1rbitro de los pueblos; destruir\u00e1n sus espadas y har\u00e1n arados de ellas y de sus lanzas podaderas. Una naci\u00f3n no se levantar\u00e1 contra otra y no aprender\u00e1n m\u00e1s el arte de la guerra\u201d (Is 2,3-4).<br \/>\nRosen retom\u00f3 tambi\u00e9n un comentario del gran rabino Meir Simcha de Dwinsk, que vivi\u00f3 hace un siglo, quien distingu\u00eda la paz del arca de No\u00e9 de la visi\u00f3n prof\u00e9tica de Isa\u00edas. Mientras que, en el primer caso, la paz era la \u00fanica posibilidad, en la visi\u00f3n de Isa\u00edas nace del \u201cconocimiento del Se\u00f1or\u201d, surge de la m\u00e1s \u00edntima comprensi\u00f3n espiritual y de la libre voluntad.<br \/>\n\u201cPara muchos en el mundo, la paz es una necesidad pragm\u00e1tica y esto es, en efecto, verdadero\u201d, observ\u00f3 Rosen, pero la paz que anhelan los hombres y las mujeres es distinta: es \u201csubir a la monta\u00f1a del Se\u00f1or\u201d, es decir, \u201cuna idea de paz como expresi\u00f3n sublime de la voluntad divina y de la imagen divina en la que todo ser humano es creado\u201d.<br \/>\nHaciendo un homenaje al beato Juan Pablo II, y expresando gratitud hacia su sucesor Benedicto XVI, el rabino record\u00f3 a los sabios del Talmud. \u201cNos ense\u00f1an &#8211;as\u00ed explic\u00f3- que la paz no s\u00f3lo es en nombre de Dios (\u2026) sino que tambi\u00e9n es el requisito indispensable para la redenci\u00f3n\u201d.<br \/>\nDiverso fue el enfoque del secretario general de la Conferencia Internacional de los Estudiosos Isl\u00e1micos (ICIS) y expresidente de Nabdlatul Ulama (NU), el indonesio Kyai Haji Hasyim Muzadi. Su reflexi\u00f3n comenz\u00f3 con la constataci\u00f3n de que \u201cmuchos problemas entre los hombres sobre esta tierra, vienen de los que siguen una religi\u00f3n\u201d, pero que esto no significa \u201cque los problemas que surgen entre los hombres que pertenecen a una religi\u00f3n sean originados por la religi\u00f3n misma\u201d.<br \/>\nPara el exponente musulm\u00e1n, lo que genera conflictos y tensiones es el simple hecho de que \u201clas religiones aut\u00e9nticas\u201d \u201cpueden tener seguidores que no son capaces de comprender su car\u00e1cter saludable de manera plena y completa\u201d, una carencia que puede llevar \u201ca la distorsi\u00f3n de la religi\u00f3n misma\u201d. \u201cToda religi\u00f3n posee identidad propia\u201d, prosigui\u00f3 Hasyim Muzadi, pero \u201cun car\u00e1cter com\u00fan de toda religi\u00f3n es la esperanza para la creaci\u00f3n de armon\u00eda entre los hombres, paz, justicia y prosperidad y un mejor nivel de vida\u201d.<br \/>\nSu receta para llegar \u201ca una armon\u00eda y coexistencia duraderas entre las religiones\u201d es sencilla: \u201cno se deber\u00eda y no se debe cambiar lo que es distinto, y no se deben imponer los puntos de vista que no se comparten\u201d, sostuvo el delegado musulm\u00e1n, que advirti\u00f3 tambi\u00e9n del peligro de instrumentalizar la religi\u00f3n. \u201cNuestro deber, como comunidades religiosas, es el de llevar a todos los creyentes la libertad de comprender verdaderamente el propio destino, y de corregir las comprensiones equivocadas de las religiones que llevan a conflictos sociales entre la humanidad\u201d.<br \/>\nLa representante de los \u201cno creyentes\u201d o agn\u00f3sticos Julia Kristeva, prefiri\u00f3, sin embargo, comenzar su reflexi\u00f3n con las conocidas palabras de Juan Pablo II: \u201c\u00a1No teng\u00e1is miedo!\u201d. Seg\u00fan la fil\u00f3sofa y psicoanalista, estas palabras no est\u00e1n dirigidas \u00fanicamente a los creyentes, porque estas alentaban a resistir el totalitarismo\u201d. \u201cEl llamamiento de ese Papa, ap\u00f3stol de los derechos humanos, nos empuja tambi\u00e9n a no temer a la cultura europea, sino, al contrario, a osar el humanismo\u201d.<br \/>\n\u201cFrente a las crisis y a las amenazas que se agravan, ha llegado la edad de la apuesta\u201d, continu\u00f3 la francesa de origen b\u00falgaro. \u201cOsamos apostar por la renovaci\u00f3n continua de las capacidades de hombres y mujeres de creer y conocer juntos. Para que en el &#8216;multiverso&#8217; de vac\u00edo, la humanidad pueda perseguir todav\u00eda su propio destino creativo a largo plazo\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los l\u00edderes religiosos del mundo rezan por la paz en As\u00eds Apreciaci\u00f3n un\u00e1nime de la iniciativa propuesta por el Papa AS\u00cdS, viernes 28 de octubre de 2011 (ZENIT.org).- Todos los l\u00edderes religiosos que participaron este jueves 27 de octubre en la Jornada de reflexi\u00f3n, di\u00e1logo y oraci\u00f3n por la paz y la justicia en el &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/la-paz-y-la-justicia-un-grito-de-toda-la-humanidad\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1137","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1137"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1137\/revisions"}],"predecessor-version":[{"id":1138,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1137\/revisions\/1138"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}