{"id":1139,"date":"2011-11-05T19:59:26","date_gmt":"2011-11-05T17:59:26","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1139"},"modified":"2011-11-05T19:59:26","modified_gmt":"2011-11-05T17:59:26","slug":"el-grito-de-montesinos-ayer-y-hoy","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-grito-de-montesinos-ayer-y-hoy\/","title":{"rendered":"El Grito de Montesinos ayer y hoy"},"content":{"rendered":"<p>Actualidad del serm\u00f3n de Montesinos<\/p>\n<p>Han pasado 500 a\u00f1os: el contexto hist\u00f3rico, cultural, econ\u00f3mico y pol\u00edtico de Am\u00e9rica Latina ha cambiado desde el grito de Montesinos. Pero desde Am\u00e9rica Latina sigue llegando al cielo el clamor de los ind\u00edgenas y afroamericanos, de los campesinos, de las mujeres, de los mineros, de los ni\u00f1os, de los ancianos que piden justicia, dignidad, salud, trabajo, educaci\u00f3n, libertad, respeto a sus culturas, el derecho a la tierra y al territorio, el poder \u201cvivir bien\u201d, una vida digna de seres humanos.<br \/>\nYa no es el imperio hispano-luso, son las multinacionales, las estructuras econ\u00f3micas neoliberales, los intereses del mercado y los nuevos poderes mundiales, los que crean diferencias abismales entre los ricos cada vez m\u00e1s ricos y los pobres cada vez m\u00e1s pobres, que ahora son masas desechables, insignificantes, despreciables, efectos colaterales de una econom\u00eda tremendamente injusta, pero que se considera pol\u00edticamente correcta[1]. A los nuevos conquistadores no les mueve el sufrimiento del pueblo, ni el destrozo de la ecolog\u00eda, ni el avasallamiento de las culturas. Siguen dormidos en un sue\u00f1o let\u00e1rgico profundo.<br \/>\nTambi\u00e9n han surgido en estos \u00faltimos a\u00f1os voces prof\u00e9ticas, verdaderos defensores de los indios, Santos Padres de Am\u00e9rica Latina, como Proa\u00f1o, M\u00e9ndez Arceo, Laguna, Samuel Ruiz, Helder C\u00e1mara, Lorscheider, Pironio, Silva Henr\u00edquez, Romero, Angelelli\u2026 los documentos de Medell\u00edn y Puebla, la teolog\u00eda de la liberaci\u00f3n, las comunidades de base, la vida religiosa inserta entre los pobres auspiciada por la CLAR\u2026 Tambi\u00e9n ha habido reacciones del imperio de turno, ha habido m\u00e1rtires en todos los sectores de la Iglesia, desde obispos, sacerdotes, religiosos y religiosas a campesinos, catequistas, ind\u00edgenas, mujeres y ni\u00f1os, gente del pueblo pueblo. Los sucesores de Fernando el Cat\u00f3lico, el \u201csistema\u201d no admite cr\u00edticas ni cuestionamientos, nunca perdona ni olvida. La pasi\u00f3n de Jes\u00fas sigue presente y actual en el pueblo sufriente, en \u201clos crucificados de la historia\u201d.<br \/>\nPero lo m\u00e1s doloroso ha sido que tambi\u00e9n desde las instancias eclesiales ha habido incomprensiones, cr\u00edticas, condenaciones y descalificaciones, a obispos, te\u00f3logos, comunidades de base, vida religiosa inserta, la CLAR; se han frenado los ministerios de los di\u00e1conos ind\u00edgenas\u2026 Son los herederos de Alonso de Loaysa que mientras condenaban estas voces prof\u00e9ticas, tild\u00e1ndolas de materialistas y comunistas, de subversivas, de poco cristianas y de poco eclesiales, de querer hacer una Iglesia popular y paralela del pueblo, enfrentada a la Iglesia jer\u00e1rquica\u2026 no ve\u00edan inconveniente en que comulgasen dictadores, aumentasen movimientos espiritualistas, prosperasen teolog\u00edas neoconservadoras como la de Michael Novak que compara al capitalismo con el Siervo de Yahv\u00e9 al que todos desprecian pero que es el \u00fanico que salva y libera (Is 53). Mientras un nuncio italiano jugaba elegantemente a tenis los fines de semana con el dictador argentino, miles de ciudadanos eran torturados y desaparec\u00edan en Buenos Aires\u2026<br \/>\nEl serm\u00f3n de Montesinos sigue siendo actual para la sociedad y la Iglesia de hoy.<br \/>\nUna reciente pel\u00edcula espa\u00f1ola, Tambi\u00e9n la lluvia de la directora Iciar Bolla\u00edn lo quiere representar. En el gui\u00f3n se escenifica la conquista de Am\u00e9rica y la opresi\u00f3n de los ind\u00edgenas con la presencia de Col\u00f3n y tambi\u00e9n de la voz de protesta de Montesinos: \u201c\u00bfestos no son hombres?\u201d Pero el rodaje de esta pel\u00edcula figura que se realiza en escenarios de Cochabamba (Bolivia) y se hace coincidir con la guerra del agua del a\u00f1o 2005, en la que los cochabambinos se sublevaron contra la multinacional propietaria del agua que quer\u00eda elevar su precio. La polic\u00eda al servicio de la multinacional reprime a los manifestantes, de modo que se reproduce la opresi\u00f3n de los conquistadores a los ind\u00edgenas. La filmaci\u00f3n se tiene que interrumpir, los actores defraudados regresan a Espa\u00f1a sin poder acabar su trabajo. Pero lo que queda patente es la cruda realidad del pueblo que sigue hoy sufriendo opresi\u00f3n. Naturalmente esta pel\u00edcula, en muchos aspectos excelente, no fue seleccionada para los premios \u00d3scar\u2026 No es pol\u00edticamente correcto recordar que la opresi\u00f3n sigue hoy. Es preferible permanecer dormidos en un sue\u00f1o let\u00e1rgico\u2026<\/p>\n<p>Algo nuevo est\u00e1 naciendo<br \/>\nLa historia nunca se repite, el contexto pol\u00edtico, social y eclesial ha cambiado profundamente, no s\u00f3lo desde tiempos de Montesinos sino tambi\u00e9n desde el final del siglo XX. Bastan algunas pinceladas impresionistas.<br \/>\nVivimos en un mundo post-marxista y post-moderno. En Am\u00e9rica Latina ya no estamos en los a\u00f1os 80, las dictaduras han dado paso a democracias, surgen algunos gobiernos de corte popular, que en medio de mil contradicciones y ambig\u00fcedades buscan revertir la situaci\u00f3n de pobreza y discriminaci\u00f3n del pueblo. El continente olvidado ahora es \u00c1frica que tambi\u00e9n comienza despertar.<br \/>\nEmerge en el mundo globalizado de hoy una gran crisis econ\u00f3mica, energ\u00e9tica, ecol\u00f3gica y civilizatoria. Ha ca\u00eddo el muro de Berl\u00edn, pero tambi\u00e9n han ca\u00eddo las torres gemelas de Nueva York. El modelo econ\u00f3mico actual naufraga, a pesar de sus continuas reflotaciones. Los desastres ecol\u00f3gicos son se\u00f1ales de alerta roja. Chernobyl y Fukushima simbolizan la crisis energ\u00e9tica y los peligros de querer ser aprendices de brujo. Estamos ante un cambio de \u00e9poca, de paradigma. Los terremotos y tsunamis no son s\u00f3lo desastres tel\u00faricos, sino que simbolizan la crisis de toda una civilizaci\u00f3n moderna y t\u00e9cnica, orgullosa de su progreso.<br \/>\nA nivel eclesial tambi\u00e9n hay terremotos y tsunamis. Despu\u00e9s del car\u00e1cter claramente restauracionista de los \u00faltimos pontificados \u2013y a pesar de grandes concentraciones masivas religiosas y de los show medi\u00e1ticos que parecen insinuar que nada pasa\u2013, la barca de Pedro se zarandea en una crisis que desde el tiempo de la Reforma no se hab\u00eda visto. Los esc\u00e1ndalos sexuales son s\u00f3lo la punta del iceberg de una profunda crisis, algo huele a podrido\u2026 La cristiandad ha explotado aunque su agon\u00eda sea lenta. J\u00f3venes y mujeres abandonan silenciosamente la Iglesia. En Am\u00e9rica Latina los representantes oficiales de la Iglesia ya no son, como en tiempo de Montesinos, la voz de los sin voz, pues los pobres y los ind\u00edgenas ya tienen voz propia. Muchos piensan que la teolog\u00eda de la liberaci\u00f3n ya ha muerto. A Roma ahora le preocupa sobre todo la teolog\u00eda asi\u00e1tica del di\u00e1logo inter-religioso.<br \/>\nEn medio de esta ca\u00f3tica situaci\u00f3n mundial y eclesial, en medio de esta crisis, en esta noche oscura, hay signos apocal\u00edpticos de que algo nuevo est\u00e1 naciendo. Hay nuevos sujetos emergentes en la sociedad y en la Iglesia: j\u00f3venes, pobres, ind\u00edgenas y afros, mujeres. Se escucha el grito de que \u201cotro mundo es posible\u201d, tambi\u00e9n de que \u201cotra Iglesia es posible\u201d.<br \/>\nComo en los or\u00edgenes de la creaci\u00f3n, en medio de la noche y del caos reinante, el Esp\u00edritu genera vida (Gn 1, 2) y hace nacer un mundo nuevo, diferente. Este caos anuncia dolores de parto de la creaci\u00f3n (Rm 8, 20), los centinelas divisan que los almendros comienzan a florecer en medio del invierno mundial y eclesial. El Esp\u00edritu del Se\u00f1or est\u00e1 activo, estos signos de muerte son preludio de resurrecci\u00f3n, la piedra del sepulcro comienza a removerse, las mujeres son las primeras en darse cuenta y en creer en la resurrecci\u00f3n[2].<br \/>\nEn este nuevo contexto el grito de Montesinos tambi\u00e9n vuelve a resonar de nuevo: \u201c\u00bfC\u00f3mo est\u00e1is en tanta profundidad de sue\u00f1o let\u00e1rgico dormidos? Tened por cierto que en el estado que est\u00e1is no os pod\u00e9is salvar\u201d. Es necesario cambiar de rumbo, despertarnos, tomar conciencia de que algo nuevo est\u00e1 naciendo (Is 43, 19), porque, hoy como ayer, el Se\u00f1or quiere hacer todas las cosas nuevas (Apoc 21, 5). En Am\u00e9rica Latina todav\u00eda estamos en tiempo de Adviento\u2026<\/p>\n<p>________________________________________<br \/>\n[1] Aparecida, 65.<br \/>\n[2] J. Moingt Les femmes et l\u00b4avenir de l\u00b4Eglise, Etudes (Paris), janvier 2011, 67- 76, que concluye con esta predicci\u00f3n prof\u00e9tica: \u201cLa mujer es y ser\u00e1 el futuro de la Iglesia\u201d.<br \/>\n* \u00c9ste art\u00edculo fue publicado en la Revista Christus de M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actualidad del serm\u00f3n de Montesinos Han pasado 500 a\u00f1os: el contexto hist\u00f3rico, cultural, econ\u00f3mico y pol\u00edtico de Am\u00e9rica Latina ha cambiado desde el grito de Montesinos. Pero desde Am\u00e9rica Latina sigue llegando al cielo el clamor de los ind\u00edgenas y afroamericanos, de los campesinos, de las mujeres, de los mineros, de los ni\u00f1os, de los &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-grito-de-montesinos-ayer-y-hoy\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1139","post","type-post","status-publish","format-standard","hentry","category-guatemala-nuestra-mision"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1139"}],"version-history":[{"count":0,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1139\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}