{"id":1228,"date":"2012-01-30T06:23:59","date_gmt":"2012-01-30T04:23:59","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1228"},"modified":"2012-01-30T06:23:59","modified_gmt":"2012-01-30T04:23:59","slug":"el-amor-verdadero-dar-la-vida","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-amor-verdadero-dar-la-vida\/","title":{"rendered":"El amor verdadero   Dar la vida&#8230;."},"content":{"rendered":"<p><strong>El amor existe<\/strong>Del hombre que ha dado la vida por su esposa, despu\u00e9s de una vida entera de amor<br \/>\nAutor: Mart\u00edn Olivares | Fuente: catolicosemprendedores.net<\/p>\n<p>La historia del naufragio del barco Costa Concordia, con 4.200 personas a bordo, ante las costas de la isla de Giglio en Italia, junto a tantos ejemplos de lo que es la fr\u00e1gil naturaleza humana, -un capit\u00e1n que, seg\u00fan lo que hasta el momento ha trascendido, despu\u00e9s de tomar la err\u00f3nea decisi\u00f3n de acercarse demasiado a tierra poniendo en peligro el barco que comandaba, se cuenta luego entre los primeros en abandonarlo para ponerse a salvo-, recoge tambi\u00e9n la bella historia de amor de una pareja felizmente casada, \u00e9l, Francis Servel, setenta y dos a\u00f1os, ella, Nicole, su esposa, sesenta, donde \u00e9l sacrific\u00f3 su vida para que la mujer de su vida pudiera salvarla.<\/p>\n<p>Se da la circunstancia de que el crucero era precisamente un regalo de los hijos por su aniversario de bodas.<\/p>\n<p>Parece ser que producida la colisi\u00f3n que provoc\u00f3 el vuelco del gigantesco trasatl\u00e1ntico, la pareja, que hab\u00eda dejado pasar por delante en las embarcaciones de salvamento a todos las personas m\u00e1s j\u00f3venes que ellos, se vio al final sin barca en la que ponerse a salvo y ante la \u00fanica tesitura de saltar al agua para salvar la vida. Por alguna circunstancia desgraciada, parece ser que se encontraron ante un solo equipo de salvamento, que era el que ten\u00eda Francis, el cual no dud\u00f3 un momento en entreg\u00e1rselo a su esposa, que no sab\u00eda nadar, tir\u00e1ndose al agua para que ella no pudiera negarse a utilizarlo. <\/p>\n<p>Tras luchar una hora contra el mar, ella, provista del equipo de salvamento, consigui\u00f3 alcanzar la costa y salvarse. El, en cambio, a pesar de pertenecer a una extensa familia de marinos siendo \u00e9l el \u00fanico que no lo era, debi\u00f3 de sucumbir contra el fr\u00edo, y tal vez tambi\u00e9n contra el agua, pues padec\u00eda un mal de espalda que probablemente le impidi\u00f3 luchar contra el l\u00edquido elemento durante mucho tiempo.<\/p>\n<p>Una bella historia de amor. Una pareja que permanece unida toda una vida, que celebra con todo el amor tantos a\u00f1os de matrimonio (no les puedo decir cu\u00e1ntos, s\u00ed puedo decirles que tienen dos hijos, Edwige y Eric, y nietos, por lo tanto varias d\u00e9cadas), y en la que, finalmente, uno da la vida para salvar al otro.<\/p>\n<p>Digan lo que digan quienes lo digan, el amor existe. El amor para toda la vida, el que no es s\u00f3lo fruto de un momento de pasi\u00f3n y es capaz de entregarlo todo por el otro hasta la vida, existe. Capaz de todo cuando reci\u00e9n nace entre las brumas de la pasi\u00f3n, pero capaz de todo tambi\u00e9n, si no de m\u00e1s, hasta de dar la vida como lo ha hecho Francis, despu\u00e9s de toda una vida de madurar, crecer, y como el mejor vino, reposar y envejecer.<\/p>\n<p>\u2022  Consultorios en l\u00ednea. Dudas personales, asesor\u00eda doctrinal y espiritual, vocacional, problemas familiares&#8230;<\/p>\n<p>\u2022  Foros de Catholic.net<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El amor existeDel hombre que ha dado la vida por su esposa, despu\u00e9s de una vida entera de amor Autor: Mart\u00edn Olivares | Fuente: catolicosemprendedores.net La historia del naufragio del barco Costa Concordia, con 4.200 personas a bordo, ante las costas de la isla de Giglio en Italia, junto a tantos ejemplos de lo que &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-amor-verdadero-dar-la-vida\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1228","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1228"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1228\/revisions"}],"predecessor-version":[{"id":1229,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1228\/revisions\/1229"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}