{"id":1274,"date":"2012-04-17T06:25:30","date_gmt":"2012-04-17T04:25:30","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1274"},"modified":"2012-04-17T06:25:30","modified_gmt":"2012-04-17T04:25:30","slug":"la-lucha-contra-la-esclavitud-infantil","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/la-lucha-contra-la-esclavitud-infantil\/","title":{"rendered":"La Lucha contra la esclavitud infantil"},"content":{"rendered":"<p>La lucha contra la esclavitud infantil hoy<br \/>\nMuchas veces ante el drama que se vive en el mundo de hoy sobre la esclavitud nfantil, hambre, miseria e injusticias pensamos que no se puede hacer nada, que ese problema no se puede erradicar,  etc.. siempre ante los dramos humanos, nos viene a todos la tentaci\u00f3n de decir  \u00bb NO SE PUEDE HACEER NADA\u00bb, pues parece que si se quiere, si se puede hacer algo&#8230; sirva esta reflexi\u00f3n para seguir sembrando vida, esperanza y solidaridad. Otro mundo es posible si se quiere hacer algo.<\/p>\n<p>Los empobrecidos siguen luchando contra la esclavitud infantil. La Campa\u00f1a por la Justicia en la Relaciones Norte-Sur del Movimiento Cultural Cristiano quiere insertarse en esta corriente de lucha solidaria.<\/p>\n<p>Son incontables las iniciativas protagonizadas por los empobrecidos que pretenden eliminar las agresiones que sigue sufriendo la infancia en todo el mundo.<\/p>\n<p>Esclavos de la violencia<\/p>\n<p>En los campos de batalla o en las guerras callejeras de las ciudades, los ni\u00f1os mueren y matan con las armas que les venden los pa\u00edses enriquecidos, Espa\u00f1a incluida. Lo denuncian misioneros javerianos que trabajan en Sierra Leona con ni\u00f1os soldado; \u201carmas fabricadas cada vez m\u00e1s ligeras y m\u00e1s f\u00e1ciles de utilizar para que las puedan empu\u00f1ar los ni\u00f1os y que ahora mismo est\u00e1n siendo fabricadas en Espa\u00f1a (\u2026) \u201d<\/p>\n<p>En Burundi la Casa Shalom trabaja por la paz y la promoci\u00f3n de los ni\u00f1os v\u00edctimas de la guerra fraticida de los a\u00f1os 90. Son m\u00e1s de 20.000 los hijos de Margarite Barankitse, muchos de los cuales \u2013ya mayores- son ahora responsables de los 3.000 hogares donde hermanos y primos hu\u00e9rfanos, est\u00e1n reconstruyendo sus vidas. Milagro surgido del horror, en el que el perd\u00f3n y la reconciliaci\u00f3n est\u00e1n haciendo posible una verdadera revoluci\u00f3n.<\/p>\n<p>En Venezuela un grupo de madres y familiares, cuyos hijos han sido asesinados por la violencia juvenil planificada, han creado la Fundaci\u00f3n por la Dignidad Sagrada de la Persona, est\u00e1n plantando cara a los responsables pol\u00edticos y econ\u00f3micos, organizando marchas y acciones de denuncia y concienciaci\u00f3n contra la impunidad.<\/p>\n<p>Esclavas sexuales<\/p>\n<p>Destacamos la labor que la fundaci\u00f3n METER est\u00e1 realizando en el combate contra la pederastia en Italia y en Europa, apoyando a los ni\u00f1os y a las familias v\u00edctimas de esta salvajada. El sacerdote Fortunato Di Noto, impulsor de la fundaci\u00f3n est\u00e1 amenazado de muerte por las mafias de la pederastia.<\/p>\n<p>En Filipinas destaca la Prevent and Rehabilitate Drug Abusers Foundation, fundada por el sacerdote Shay Cullen y el matrimonio filipino de Merle y Alex Hermoso. Su labor se desarrolla en la Bah\u00eda de Subic, donde se aloj\u00f3 la base militar norteamericana m\u00e1s grande fuera del territorio de EEUU hasta 1992, dejando en la zona un grave problema de prostituci\u00f3n, droga y enfermedades de transmisi\u00f3n sexual. Hoy contin\u00faan apoyando a las v\u00edctimas de la prostituci\u00f3n infantil y denunciando a los causantes.<\/p>\n<p>Somaly Mam, en Camboya, fue ni\u00f1a prostituida y tras conseguir escapar de ese infierno en 1991, decidi\u00f3 volver a su pa\u00eds para luchar por la dignidad de sus compatriotas prostituidas.<\/p>\n<p>Esclavos del hambre<\/p>\n<p>El drama del hambre convive con la opulencia en pa\u00edses ricos como Argentina. La organizaci\u00f3n Chicos del Pueblo lleva a\u00f1os organizando marchas protagonizadas por los propios ni\u00f1os para denunciar que \u201cEl hambre es un crimen\u201d. Esta experiencia comenz\u00f3 en la humilde capilla de Florencio Varela, (Buenos Aires), en los hogares de la fundaci\u00f3n \u201cPelota de Trapo\u201d y \u201cMadre tres veces admirable\u201d apoyados por la Iglesia cat\u00f3lica, crearon un agencia propia de noticias; han sufrido diversos ataques a su imprenta, secuestros y amenazas a varios educadores.<\/p>\n<p>Esclavos laborales<\/p>\n<p>En 2001 naci\u00f3 en Argentina la asociaci\u00f3n La Alameda, en la \u00e9poca del corralito financiero y r\u00e1pidamente comenz\u00f3 a denunciar la explotaci\u00f3n de familias bolivianas (ni\u00f1os incluidos) en talleres textiles clandestinos que trabajan para empresas multinacionales como Adidas, Fila y Puma.<\/p>\n<p>En 2004 pusieron en marcha la Cooperativa 20 de Diciembre, que se ha asociado con otras cooperativas de trabajo digno de Tailandia. En 2006 naci\u00f3 el Movimiento de Trabajadores Excluidos entre los cartoneros, denuncian tambi\u00e9n la explotaci\u00f3n infantil en los campos y en los prost\u00edbulos (con complicidad de las mafias policiales) y han recibido el apoyo del Cardenal Bergoglio.<\/p>\n<p>En la India y Paquist\u00e1n, son numerosos los testimonios de lucha como el de Iqbal Masih, ni\u00f1o esclavo asesinado a los 12 a\u00f1os en Pakist\u00e1n por su lucha contra las mafias tapiceras. Praveen Kumar, ni\u00f1o esclavo en Thallur- India, fue responsable de un sindicato de 14.000 ni\u00f1os menores de 17 a\u00f1os y donde algunos no pasaban de los 7.<\/p>\n<p>En la India destaca la labor de Kailash Satyarthi y la organizaci\u00f3n BBA, que ha logrado liberar a 78.500 ni\u00f1os (sufriendo episodios de violencia por parte de los esclavistas). Tienen numerosos centros educativos. Su labor la realizan mediante largas marchas como la de 1992 de 2.000 km desde la zona de las alfombras (Bihar) a Delhi, la de Calcuta hasta Katmand\u00fa en 1994 (1.500 km) y as\u00ed hasta la actualidad.<\/p>\n<p>El Frente de Liberaci\u00f3n del Trabajo Forzado (India y Pakist\u00e1n) es un gran movimiento contra la esclavitud infantil, creado en 1981 por Swami Agnivesh, l\u00edder espiritual hind\u00fa que anteriormente hab\u00eda creado un partido pol\u00edtico frente al comunismo y el capitalismo. Estuvo 14 meses en prisi\u00f3n y lleg\u00f3 a ser Ministro de educaci\u00f3n, pero tuvo que dimitir. Luchan contra el sistema de castas, la persecuci\u00f3n a los cristianos y el feticidio femenino. Han conseguido liberar a 172.000 ni\u00f1os y han creado diversas instituciones educativas y de formaci\u00f3n profesional. Han fundado asociaciones y sindicatos para presionar a los representantes pol\u00edticos contra la esclavitud infantil. La rama de Pakist\u00e1n fue creada en 1988 por Ehsan Ullah Khan, en este movimiento Iqbal Masih, fue presidente de la Secci\u00f3n infantil. Tras su asesinato, el movimiento sufri\u00f3 una fuerte persecuci\u00f3n y difamaci\u00f3n por parte del gobierno. Ehsan se exili\u00f3 a Inglaterra y perdieron el apoyo financiero que ten\u00edan de una ONG sueca y de UNICEF. Superada la crisis, contin\u00faan organizando la liberaci\u00f3n de decenas de miles de ni\u00f1os.<\/p>\n<p>La lucha de Iqbal se extiende<\/p>\n<p>La noticia del asesinato de Iqbal en 1995, pas\u00f3 casi desapercibida en Espa\u00f1a excepto a Juli\u00e1n G\u00f3mez del Castillo, viejo militante cristiano con la sensibilidad y la visi\u00f3n necesaria para impulsar y ser altavoz de las luchas de los ni\u00f1os esclavos. Desde entonces el Movimiento Cultural Cristiano, CJS y m\u00e1s recientemente el partido SAIn vienen realizando en Espa\u00f1a y en Iberoam\u00e9rica cientos de actos p\u00fablicos convirtiendo de hecho al 16 de Abril (aniversario del martirio de Iqbal) en el d\u00eda Mundial contra la Esclavitud Infantil. Han forzado que este drama aparezca en los medios de comunicaci\u00f3n, rompiendo el silencio. Su labor de conciencia est\u00e1 basada en el trabajo gratuito de los militantes, sin subvenciones y con la oposici\u00f3n creciente de la administraci\u00f3n.<\/p>\n<p>En Italia existen campa\u00f1as como las de La Asociaci\u00f3n Iqbal Masih de Sicilia, desde 1995. La asociaci\u00f3n Mantovan que organiza desde 1999 una jornada el 16 de Abril que involucraba todo el pa\u00eds, incluso al Presidente de la Rep\u00fablica&#8230;<\/p>\n<p>En Canad\u00e1: Free the Children; en EEUU: School for Iqbal, asociaci\u00f3n que surgi\u00f3 en un colegio a ra\u00edz de una charla impartida por el propio Iqbal.<\/p>\n<p>Conclusi\u00f3n<\/p>\n<p>Es mentira aquello de \u201cno se puede hacer nada\u201d. Estas experiencias nos vuelven a demostrar la fuerza de la debilidad. Basta con ponerse en marcha, desde el protagonismo de los d\u00e9biles, pensando con cabeza propia, con autofinanciaci\u00f3n y sin depender de los poderosos, podemos seguir enciendo cerillas de solidaridad en medio de la oscuridad. De nosotros depende.<\/p>\n<p>Autor: Equipo Felipe L\u00f3pez- Fecha: 2012-04-11  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lucha contra la esclavitud infantil hoy Muchas veces ante el drama que se vive en el mundo de hoy sobre la esclavitud nfantil, hambre, miseria e injusticias pensamos que no se puede hacer nada, que ese problema no se puede erradicar, etc.. siempre ante los dramos humanos, nos viene a todos la tentaci\u00f3n de &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/la-lucha-contra-la-esclavitud-infantil\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1274","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1274"}],"version-history":[{"count":2,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1274\/revisions"}],"predecessor-version":[{"id":1276,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1274\/revisions\/1276"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}