{"id":1450,"date":"2013-03-11T02:08:26","date_gmt":"2013-03-11T00:08:26","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1450"},"modified":"2013-03-11T02:08:26","modified_gmt":"2013-03-11T00:08:26","slug":"el-futuro-papa","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-futuro-papa\/","title":{"rendered":"El futuro papa.."},"content":{"rendered":"<p>El cardenal arzobispo de Nueva York se encuentra en Roma desde que llegase para despedir a Benedicto XVI. Nost\u00e1lgico de su tierra ha escrito una carta a sus feligreses en las que les cuenta c\u00f3mo est\u00e1 viviendo todo este tiempo desde la capital italiana ante el inminente C\u00f3nclave.<\/p>\n<p>De la carta muchos medios se han centrado en que supuestamente el cardenal Timothy Dolan augura un cambio radical en la Iglesia con el pr\u00f3ximo Papa y sin embargo se pierden una carta de lo m\u00e1s entra\u00f1able que adem\u00e1s resume a la perfecci\u00f3n lo que all\u00ed se est\u00e1 viviendo.<\/p>\n<p>A pesar de todo, Dolan no puede dejar de lado su sentido del humor y evoca canciones como \u201cI wanna go home\u201d para decir lo que anhela Nueva York. Igualmente, asegura que va a echar de menos a todos especialmente el d\u00eda de San Patricio, el pr\u00f3ximo 17 de marzo y bromeando asegura que en Roma \u201cno he podido encontrar ning\u00fan pan irland\u00e9s, carne asada y whisky\u201d (Aclara que es una broma).<\/p>\n<p>El nombre que m\u00e1s suena: Cristo<br \/>\nEn este sentido, relata a los diocesanos de Nueva York algo que muchos periodistas querr\u00edan saber: de qui\u00e9n se habla m\u00e1s cuando se re\u00fanen los cardenales. Consciente de que estos d\u00edas circulan numerosos nombres de cardenales, Dolan afirma que \u201cclaro\u201d que surgen nombres pero \u201cel m\u00e1s nombrado\u201d entre los cardenales es sin duda el de \u201cnuestro Se\u00f1or Jesucristo\u201d. Y lo cuenta as\u00ed sabiendo que muchos est\u00e1n obviando  que el centro de todo es Cristo. Por eso pide a los neoyorkinos que pidan a este \u201ctan nombrado\u201d para que env\u00ede a los pr\u00edncipes de la Iglesia su \u201cgracia\u201d.<\/p>\n<p>Sobre sus d\u00edas en Roma, el arzobispo de Nueva York se sincera de una manera conmovedora y asegura que una persona mayor le dijo que el final de un Pontificado y la elecci\u00f3n de un nuevo Papa \u201cson como los d\u00edas en Jerusal\u00e9n despu\u00e9s de la Ascensi\u00f3n de Nuestro Se\u00f1or a los cielos. Toda la Iglesia oraba, oraba mucho, rez\u00f3 largo tiempo, unidos a los ap\u00f3stoles y a la Madre de Jes\u00fas, que estaban encerrados en el Cen\u00e1culo, en espera del don supremo del Esp\u00edritu Santo\u201d. \u201cEso est\u00e1 sucediendo ahora\u201d, afirma.<\/p>\n<p>Los cardenales, como en el Cen\u00e1culo<br \/>\nPor ello, les explica en la carta que \u201clos cardenales estamos rezando mucho y todos los d\u00edas cada uno de nosotros comienza con la oraci\u00f3n m\u00e1s eficaz de todas, el Santo Sacrificio de la Misa\u201d.<\/p>\n<p>De este modo, indica que en realidad el Colegio de Cardenales pero tambi\u00e9n toda la Iglesia \u201cestamos de vuelta en ese Cen\u00e1culo con la Virgen y los ap\u00f3stoles y los desaf\u00edos que nosotros \u2013y el nuevo San Pedro- nos enfrentamos son, sorprendentemente, similares a los del primer Papa ante el primer Pentecost\u00e9s: c\u00f3mo presentar a la persona el mensaje y la invitaci\u00f3n de Jes\u00fas a un mundo que, durante la b\u00fasqueda de la salvaci\u00f3n y la verdad eterna, tambi\u00e9n a veces duda,  es demasiado esc\u00e9ptico y est\u00e1 ocupado o frustrado\u201d.<\/p>\n<p>En este sentido, agu\u00f3 la fiesta a los que pensaban en conspiraciones y peleas entre los cardenales. \u201cPuedes quedarte sorprendido al o\u00edr \u2013relata &#8211; que pasamos la mayor parte de nuestro tiempo comentando temas como la predicaci\u00f3n, la ense\u00f1anza de la fe, los sacramentos\u2026.Y as\u00ed Dolan cit\u00f3 a los enfermos, religiosos, seminaristas, alejados de la fe, organizaciones caritativas, familias, matrimonio, vida, aborto\u2026Y deja muy claro que eso son los \u201cgrandes temas\u201d y no otros.<\/p>\n<p>\u00bfDe qu\u00e9 hablan realmente los cardenales?<br \/>\nEl cardenal estadounidense avisa a los feligreses de su di\u00f3cesis que aunque les cueste cre\u00e9rselo, pues en la calle aparece que s\u00f3lo se habla de corrupci\u00f3n en el Vaticano, abusos sexuales y dinero, estos no son los \u201cgrandes temas\u201d. \u201c\u00bfEstos temas salen? \u00a1S\u00ed! \u00bfSon los que dominan? \u00a1No!\u201d. M\u00e1s claro, el agua.<\/p>\n<p>Para acabar la carta, el arzobispo de Nueva York cuenta la an\u00e9cdota que le ha ocurrido con uno de los 5000 periodistas que est\u00e1n en Roma estos d\u00edas y que est\u00e1n \u00e1vidos de cualquier tipo de noticia. Este hecho adem\u00e1s muestra su personalidad y su curiosa forma de actuar.<\/p>\n<p>La an\u00e9cdota con la periodista<br \/>\nAfirma que uno de ellos le pregunt\u00f3 si el nuevo Papa podr\u00eda traer un \u201ccambio radical\u201d a la Iglesia. Cuenta monse\u00f1or Dolan que le contest\u00f3 que s\u00ed ante la sorpresa de la reportera. \u201cPor lo menos ten\u00eda toda su atenci\u00f3n. Entonces proced\u00ed a aclararle que la Iglesia es de \u2018grandes cambios, es decir, un cambio en el coraz\u00f3n humano, que Jes\u00fas llam\u00f3 arrepentimiento o conversi\u00f3n\u201d. As\u00ed comenz\u00f3 a catequizarla y a explicarla que la labor del obispo de Roma es el de \u201cconservar la fe, las verdades que han sido reveladas por Dios, sobre todo a trav\u00e9s de su hijo, Jes\u00fas, fielmente transmitida por Su Iglesia en estos \u00faltimos 2000 a\u00f1os y la de renovar la invitaci\u00f3n de Jes\u00fas a un cambio de coraz\u00f3n\u201d. \u00bfTe parece un cambio peque\u00f1o?<\/p>\n<p>Poco despu\u00e9s y tras hacerse p\u00fablica la fecha del C\u00f3nclave hizo una petici\u00f3n a sus diocesanos para que ilumine a todos los cardenales en este momento tan importante para la Iglesia. Les invita a rezar la Novena a San Jos\u00e9, para que junto a la Virgen Mar\u00eda les ayude y exhorte en este tiempo, fiesta que se celebra el 19 de marzo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cardenal arzobispo de Nueva York se encuentra en Roma desde que llegase para despedir a Benedicto XVI. Nost\u00e1lgico de su tierra ha escrito una carta a sus feligreses en las que les cuenta c\u00f3mo est\u00e1 viviendo todo este tiempo desde la capital italiana ante el inminente C\u00f3nclave. De la carta muchos medios se han &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-futuro-papa\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1450","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1450"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1450\/revisions"}],"predecessor-version":[{"id":1451,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1450\/revisions\/1451"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}