{"id":1783,"date":"2015-05-25T13:58:20","date_gmt":"2015-05-25T11:58:20","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1783"},"modified":"2015-05-25T13:58:37","modified_gmt":"2015-05-25T11:58:37","slug":"beatificacion-del-p-jordan","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/beatificacion-del-p-jordan\/","title":{"rendered":"BEATIFICACION DEL P. JORDAN"},"content":{"rendered":"<p>Estado actual del proceso de beatificaci\u00f3n del<br \/>\nVenerable P. Francisco Mar\u00eda de la Cruz Jord\u00e1n.<\/p>\n<p>El 19 de marzo de 2011, en nuestra Casa Madre, el Prefecto de la Congregaci\u00f3n para las Causas de los Santos promulg\u00f3 oficialmente el decreto sobre la heroicidad de las virtudes de nuestro Padre Fundador. De esta manera el proceso sobre la vida y virtudes del Padre Jord\u00e1n lleg\u00f3 a una conclusi\u00f3n, porque la Iglesia reconoci\u00f3 oficialmente que el P. Jord\u00e1n llev\u00f3 una vida ejemplar y practic\u00f3 las virtudes cristianas en grado heroico! <\/p>\n<p>El XVIII cap\u00edtulo general de los salvatorianos pidi\u00f3 que se promueva la veneraci\u00f3n del P. Jord\u00e1n para su beatificaci\u00f3n.<br \/>\nEl fundamento de esta petici\u00f3n es que siempre hemos cre\u00eddo que nuestro fundador es un santo. La Iglesia universal as\u00ed lo reconoci\u00f3 cuando el 14 de enero de 2011 promulg\u00f3 la heroicidad de las virtudes del venerable siervo de Dios P. Francisco Mar\u00eda de la Cruz Jord\u00e1n. Cabe recordar que con este importante paso  se ha abierto el camino a su beatificaci\u00f3n. Para lograr esto es necesario seguir pidiendo gracias por intercesi\u00f3n del siervo de Dios. Se debe intensificar la oraci\u00f3n para obtener un posible milagro por intercesi\u00f3n del P. Jord\u00e1n.<br \/>\nPara orar a Dios por intercesi\u00f3n del P. Jord\u00e1n es importante tener una relaci\u00f3n personal con  \u00e9l. Y esta se adquiere  a medida que le vamos conociendo. Por eso todos estamos llamados a \u201cestudiar\u201d su vida, su manera de pensar, su espiritualidad, su visi\u00f3n y su teolog\u00eda. Sin este contacto nos es imposible amarle y conocerle verdaderamente y tampoco ser\u00e1 f\u00e1cil orar a Dios mediante su intercesi\u00f3n.<br \/>\nAlgunos se preguntan si la beatificaci\u00f3n del P. Jord\u00e1n  aporta algo positivo. Mas hay que decir que es una manera de poner de relieve la obra del Esp\u00edritu Santo en la vida del P. Jord\u00e1n mismo; el logro del P. Jord\u00e1n es expresi\u00f3n de la voluntad de Dios en el mundo de su tiempo. La beatificaci\u00f3n significa el reconocimiento de que el P. Jord\u00e1n vivi\u00f3 su vocaci\u00f3n cristiana y su vocaci\u00f3n de fundador en forma extraordinaria y por eso es un modelo de c\u00f3mo vivir el evangelio de Jes\u00fas.<br \/>\nEl intensificar la veneraci\u00f3n al  P. Jord\u00e1n es un est\u00edmulo a los esfuerzos apost\u00f3licos de los salvatorianos, as\u00ed como fermento para la renovaci\u00f3n de la vida espiritual en nuestros d\u00edas de crisis y cambios profundos.<br \/>\nNo dejar de comunicar a la oficina de postulaci\u00f3n en Roma  las gracias obtenidas por su intercesi\u00f3n. <\/p>\n<p>  Oficina de Postulaci\u00f3n. Via Della Conciliaziones 51 00193 ROMA Italia.<\/p>\n<p>P. Francisco Jordan<br \/>\n&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;<br \/>\n* 16.06.1848   &#8211;   \u2020 08.09.1918<\/p>\n<p>Se\u00f1or Jesucristo, Salvador del mundo. T\u00fa llamaste al Padre Francisco Mar\u00eda de la Cruz Jord\u00e1n para ser tu ap\u00f3stol, para que tu Padre sea conocido y amado por todas las personas, en todos los lugares y por todos los medios que tu amor inspira. <\/p>\n<p>T\u00fa le colmaste de celo apost\u00f3lico universal, de bondad y caridad en su ministerio, de profunda confianza en Dios, de intenso esp\u00edritu de oraci\u00f3n, de sincera devoci\u00f3n a Mar\u00eda, Madre del Salvador y de pasi\u00f3n para seguirte hasta el misterio de la Cruz. <\/p>\n<p>Conc\u00e9dele ser reconocido como Santo por la Iglesia Universal. <\/p>\n<p>Y a nosotros, tus seguidores, conc\u00e9denos la gracia de proclamar el Evangelio con este esp\u00edritu y hacernos ap\u00f3stoles efectivos en el mundo de hoy. <\/p>\n<p>Por intercesi\u00f3n de tu Siervo Francisco, te pedimos por esta especial necesidad\u2026<br \/>\n A ti que vives y reinas con el Padre y el Esp\u00edritu Santo, por los siglos de los siglos. Am\u00e9n. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estado actual del proceso de beatificaci\u00f3n del Venerable P. Francisco Mar\u00eda de la Cruz Jord\u00e1n. El 19 de marzo de 2011, en nuestra Casa Madre, el Prefecto de la Congregaci\u00f3n para las Causas de los Santos promulg\u00f3 oficialmente el decreto sobre la heroicidad de las virtudes de nuestro Padre Fundador. De esta manera el proceso &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/beatificacion-del-p-jordan\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-1783","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias","category-general"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1783"}],"version-history":[{"count":2,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1783\/revisions"}],"predecessor-version":[{"id":1785,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1783\/revisions\/1785"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}