{"id":1810,"date":"2015-11-07T00:37:09","date_gmt":"2015-11-06T22:37:09","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1810"},"modified":"2015-11-07T00:37:09","modified_gmt":"2015-11-06T22:37:09","slug":"solidaridad-desde-lo-pequeno-aprendamos-la-leccion","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/solidaridad-desde-lo-pequeno-aprendamos-la-leccion\/","title":{"rendered":"Solidaridad desde lo peque\u00f1o.. aprendamos la leccion"},"content":{"rendered":"<p>Domingo trig\u00e9simo segundo del tiempo ordinario<br \/>\nLectura orante del Evangelio: Marcos 12,38-44<br \/>\n\u201cEl alma que de veras a Dios ama, no empereza hacer cuanto puede por hallar al Hijo de Dios, su Amado; y aun despu\u00e9s que lo ha hecho todo, no se satisface ni piensa que ha hecho nada\u201d (Juan de la Cruz, CB 3,1).<br \/>\n\u2018\u00a1Cuidado con los escribas!\u2019 Tambi\u00e9n en nuestra oraci\u00f3n puede haber falsedad. \u00a1Cuidado! Tambi\u00e9n puede haber vanidad, af\u00e1n de ostentaci\u00f3n, orgullo. \u00a1Cuidado! Tambi\u00e9n puede ser una excusa m\u00e1s para alimentar el ego. \u00a1Cuidado! Es incre\u00edble la facilidad con que nos consideramos mejores, superiores, primeros, y la facilidad con que marginamos y despreciamos a otros como malos, \u00faltimos, perdedores, indignos. Una oraci\u00f3n as\u00ed es falsa y, adem\u00e1s, hace da\u00f1o. Dios dispersa a los soberbios. Una religi\u00f3n sin fe es un peligro que siempre nos acecha y que tiene muchos adeptos. Ven Esp\u00edritu, Se\u00f1or. Ay\u00fadanos a andar en verdad. Ens\u00e9\u00f1anos a orar en verdad.<br \/>\nJes\u00fas sentado enfrene del cepillo del templo, observaba a la gente que iba echando dinero. La cosa va de miradas. \u00a1Cu\u00e1nto hacemos para mirarnos! \u00a1Cu\u00e1nto para ser mirados y admirados! El mundo tiene ojos para mirar apariencias. La mirada de Jes\u00fas es otra cosa, no es neutral, va a contracorriente, desmonta nuestras mentiras y tinglados espirituales de dominio sobre los otros, saca a la luz la verdad que esconde nuestro coraz\u00f3n. La oraci\u00f3n es dejar que Jes\u00fas, sentado en nuestra interioridad, nos mire. Jes\u00fas, nos ponemos confiadamente a la luz de tu mirada.<br \/>\nMuchos ricos echaban en cantidad; se acerc\u00f3 una viuda pobre y ech\u00f3 dos reales. Tintineo sonoro de las monedas de oro frente al sonido imperceptible de dos reales de bronce. Dominio de la escena de los que creen que dan y hacen m\u00e1s que nadie frente a la abajada invisibilidad de los que no cuentan, ni valen, ni dan. Oraci\u00f3n de un ego tan ensalzado, incapaz de ver al t\u00fa frente a la oraci\u00f3n de una mujer pobre que da su pobreza. \u00bfQu\u00e9 mira Jes\u00fas? \u00bfEn qui\u00e9n pone los ojos? Mira a los que nadie mira, levanta del polvo a los peque\u00f1os, alza de la basura al pobre, abraza a los que no son nada. M\u00edranos, Jes\u00fas, con tu mirada de amor; esta ser\u00e1 nuestra inesperada riqueza.<br \/>\nOs aseguro que esa pobre viuda ha echado\u2026 m\u00e1s que nadie. Una pobre, que no est\u00e1 sentada en la c\u00e1tedra, ense\u00f1a a vivir el Evangelio. Una mujer, de fe sencilla y coraz\u00f3n generoso, es la que m\u00e1s se parece a Jes\u00fas. Una viuda desamparada, al darse del todo al Todo de una forma callada, dice que Dios quiere ser Todo en todos. Una insignificante que ama es lo mejor de la Iglesia, es espejo para los que oramos y nos tenemos por entendidos en las cosas de Dios. \u00a1Cu\u00e1nto necesitamos a los pobres y sencillos para creer en Ti, para conocerte y amarte a Ti!<br \/>\nLos dem\u00e1s han echado de lo que les sobra, pero \u00e9sta, que pasa necesidad, ha echado todo lo que ten\u00eda para vivir. O jugar a dar sin dar ni darnos por entero o dejar que sea el coraz\u00f3n creyente quien hable; o acumular en la estrechez de miras o compartir ampliando los horizontes del coraz\u00f3n; o enga\u00f1ar a Dios o confiar totalmente en \u00c9l viviendo una generosidad sin l\u00edmites. Gracias, Jes\u00fas, por los que aman de verdad.<br \/>\nNo cuenta la cantidad, cuenta la calidad\u2026\u2026Un abrazo y mi oraci\u00f3n. Jos\u00e9 Antonio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domingo trig\u00e9simo segundo del tiempo ordinario Lectura orante del Evangelio: Marcos 12,38-44 \u201cEl alma que de veras a Dios ama, no empereza hacer cuanto puede por hallar al Hijo de Dios, su Amado; y aun despu\u00e9s que lo ha hecho todo, no se satisface ni piensa que ha hecho nada\u201d (Juan de la Cruz, CB &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/solidaridad-desde-lo-pequeno-aprendamos-la-leccion\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1810","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1810"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1810\/revisions"}],"predecessor-version":[{"id":1811,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1810\/revisions\/1811"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}