{"id":1884,"date":"2016-07-20T13:17:02","date_gmt":"2016-07-20T11:17:02","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1884"},"modified":"2016-07-20T13:17:02","modified_gmt":"2016-07-20T11:17:02","slug":"claves-para-una-vida-feliz","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/claves-para-una-vida-feliz\/","title":{"rendered":"CLAVES PARA UNA VIDA FELIZ"},"content":{"rendered":"<p>Bueno, si sabemos buscar y seguir a Jes\u00fas y su evangelio encontraremos las claves para que la vida sea m\u00e1s humana, m\u00e1s solidaria, m\u00e1s fraterna, mas justa y verdadera para todos. La Palabra de Dios no enga\u00f1a y da luz para el caminar de cada d\u00eda. Chema sds.<\/p>\n<p>ZENIT \u2013 Roma).- Todo el mundo quiere ser feliz. Veamos un indicador. Si vamos ahora mismo al buscador Google la voz feliz aparece doscientos diez mil millones de veces. Mientras que lo contrario a la felicidad, esto es, la tristeza son apenas treinta y un millones cien mil veces.  Una vez m\u00e1s notamos que todos queremos la felicidad.<br \/>\nEn efecto todo vale la pena si nos hace felices. Nada tiene sentido si deja de lado la felicidad. Pero \u00bfqu\u00e9 es la felicidad? \u00bfC\u00f3mo ser feliz? \u00bfD\u00f3nde encontrarla? \u00bfCu\u00e1nto tiempo dura? Saberlo es una tarea apasionante y la clave est\u00e1 en acertar.<br \/>\nPodr\u00edamos quedarnos con tres ideas ejes y son: s\u00e9 t\u00fa mismo, s\u00e9 libre y ama. Veamos una por una.<br \/>\nS\u00e9 t\u00fa mismo. Significa conocerte quien eres y cu\u00e1les son tus potencialidades. Tu luz es la verdad y t\u00fa verdad. Es importante valorarte como alguien, no como algo. Lo has recibido todo. Tu condici\u00f3n es de administrar diversos aspectos: bienes, talentos, personas, tradiciones. Tu clima debe ser las cosas como son, no ocultes ni dejes nada que pueda obstaculizar tu crecimiento personal. Esto nada tiene que ver con el conformismo o la indiferencia o el todo da lo mismo.<br \/>\nS\u00e9 libre. Has las cosas porque son buenas para ti, pero la mediada es la realidad misma que te hacen buena persona. En cuanto te decidas a enriquecer tu propia condici\u00f3n de persona por el bien que elijas en tus actos ser\u00e1s m\u00e1s feliz. Pero \u00bfqu\u00e9 es el bien? Aquello que te hace crecer, es conveniente y te acerca al fin \u00faltimo.<br \/>\nAma. Amar es un verbo que significa actividad, salida de s\u00ed mismo para encontrar un amor m\u00e1s grande que lo humano, esto es, el amor divino. Acude a la fuente del Amor y que tu recipiente cu\u00e1nto m\u00e1s grande sea mejor ser\u00e1, porque quieres amar mucho. Fortalece tu capacidad de donaci\u00f3n con lo que m\u00e1s te cueste y no te suponga simple utilidad. Dice el dicho \u201cm\u00e1s vale dar que recibir\u201d. Si quieres ser feliz comienza ya con: s\u00e9 t\u00fa mismo, s\u00e9 libre y ama.<br \/>\nP. Arnaldo Alvarado<br \/>\nSSJ \u2013 IESPPSJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bueno, si sabemos buscar y seguir a Jes\u00fas y su evangelio encontraremos las claves para que la vida sea m\u00e1s humana, m\u00e1s solidaria, m\u00e1s fraterna, mas justa y verdadera para todos. La Palabra de Dios no enga\u00f1a y da luz para el caminar de cada d\u00eda. Chema sds. ZENIT \u2013 Roma).- Todo el mundo quiere &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/claves-para-una-vida-feliz\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1884","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1884"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1884\/revisions"}],"predecessor-version":[{"id":1885,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1884\/revisions\/1885"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}