{"id":1890,"date":"2016-07-30T12:03:34","date_gmt":"2016-07-30T10:03:34","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=1890"},"modified":"2016-07-30T12:03:34","modified_gmt":"2016-07-30T10:03:34","slug":"francisco-a-los-jovenes-esperanza-de-un-mundo-nuevo","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/francisco-a-los-jovenes-esperanza-de-un-mundo-nuevo\/","title":{"rendered":"Francisco a los jovenes..esperanza de un Mundo nuevo"},"content":{"rendered":"<p>Queridos j\u00f3venes, muy buenas tardes.<br \/>\nFinalmente nos encontramos. Gracias por esta calurosa bienvenida. Gracias al Cardenal Dziwisz, a los Obispos, sacerdotes, religiosos y religiosas, seminaristas y a todos aquellos que los acompa\u00f1an. Gracias a los que han hecho posible que hoy estemos aqu\u00ed, que se la \u00abhan jugado\u00bb para que pudi\u00e9ramos celebrar la fe. O sea, celebrar la fe. Hoy nosotros aqu\u00ed todos juntos estamos celebrando la fe.<br \/>\nEn esta, su tierra natal, quisiera agradecer especialmente a san Juan Pablo II, que so\u00f1\u00f3 e impuls\u00f3 estos encuentros. Desde el cielo nos est\u00e1 acompa\u00f1ando viendo a tantos j\u00f3venes pertenecientes a pueblos, culturas, lenguas tan diferentes con un solo motivo: celebrar a Jes\u00fas que est\u00e1 vivo en medio de nosotros. \u00bfLo han entendido? Celebrar a Jes\u00fas que est\u00e1 vivo en medio de nosotros. Y decir que est\u00e1 vivo, es querer renovar nuestras ganas de seguirlo, nuestras ganas de vivir con pasi\u00f3n su seguimiento.<br \/>\n\u00a1Qu\u00e9 mejor oportunidad para renovar la amistad con Jes\u00fas que afianzando la amistad entre ustedes! \u00a1Qu\u00e9 mejor manera de afianzar nuestra amistad con Jes\u00fas que compartirla con los dem\u00e1s! \u00a1Qu\u00e9 mejor manera de vivir la alegr\u00eda del Evangelio que queriendo \u00abcontagiar\u00bb su Buena Noticia en tantas situaciones dolorosas y dif\u00edciles!<br \/>\nJes\u00fas es quien nos ha convocado a esta 31 Jornada Mundial de la Juventud; es Jes\u00fas quien nos dice: \u00abFelices los misericordiosos, porque encontrar\u00e1n misericordia\u00bb (Mt 5,7). Felices aquellos que saben perdonar, que saben tener un coraz\u00f3n compasivo, que saben dar lo mejor de s\u00ed a los dem\u00e1s. Lo mejor, no lo que le sobra, lo mejor.<br \/>\nQueridos j\u00f3venes, en estos d\u00edas Polonia, esta noble tierra se viste de fiesta; en estos d\u00edas Polonia, quiere ser el rostro siempre joven de la Misericordia. Desde esta tierras con ustedes y tambi\u00e9n unidos a tantos j\u00f3venes que hoy no pueden estar aqu\u00ed, pero que nos acompa\u00f1an a trav\u00e9s de los diversos medios de comunicaci\u00f3n, todos juntos vamos a hacer de esta jornada una aut\u00e9ntica fiesta Jubilar, en este jubileo de la Misericordia.<br \/>\nEn los a\u00f1os que llevo como obispo he aprendido una cosa, he aprendido tantas pero una quiero decirla ahora: no hay nada m\u00e1s hermoso que contemplar las ganas, la entrega, la pasi\u00f3n y la energ\u00eda con que muchos j\u00f3venes viven la vida. Esto es hermoso.<br \/>\n\u00bfY de d\u00f3nde viene esta belleza? Cuando Jes\u00fas toca el coraz\u00f3n de un joven, de una joven, estos son capaces de actos verdaderamente grandiosos. Es estimulante escucharlos, compartir sus sue\u00f1os, sus interrogantes y sus deseos y sus ganas de rebelarse contra todos aquellos que dicen que las cosas no pueden cambiar. A quienes llamo los \u2018quietistas\u2019, nada se puede cambiar. No, los j\u00f3venes tienen esa fuerza para oponerse a estos. Pero algunos no est\u00e1n seguro de esto. Y les pregunto \u00bfYo les pregunto,  las cosas se pueden cambiar?<br \/>\nBien. Es un regalo del cielo poder verlos a muchos de ustedes que, con sus cuestionamientos, buscan hacer que las cosas sean diferentes. Es lindo, y me conforta el coraz\u00f3n, verlos tan exhuberantes. La Iglesia hoy les mira, dir\u00e9 a\u00fan m\u00e1s, el mundo hoy les mira y quiere aprender de ustedes para renovar su confianza en que la Misericordia del Padre tiene rostro siempre joven y no deja de invitarnos a ser parte de su Reino, que es un Reino de alegr\u00eda, de felicidad que siempre nos lleva adelante. Es un Reino capaz de darnos la fuerza de cambiar las cosas. Me he olvidado, \u00bfLas cosas se pueden cambiar? \u2026 De acuerdo\u2026<br \/>\nConociendo la pasi\u00f3n que ustedes le ponen a la misi\u00f3n, me animo a repetir: la misericordia siempre tiene rostro joven. Porque un coraz\u00f3n misericordioso se anima a salir de su comodidad; un coraz\u00f3n misericordioso sabe ir al encuentro de los dem\u00e1s, logra abrazar a todos. Un coraz\u00f3n misericordioso sabe ser refugio para quienes nunca tuvieron casa o la han perdido; sabe construir hogar y familia para aquellos que han tenido que emigrar, sabe de ternura y compasi\u00f3n.<br \/>\nUn coraz\u00f3n misericordioso, sabe compartir el pan con el que tiene hambre, un coraz\u00f3n misericordioso se abre para recibir al pr\u00f3fugo y al migrante. Decir misericordia junto a ustedes, es decir oportunidad, es decir ma\u00f1ana, es decir compromiso, es decir confianza, apertura, hospitalidad, compasi\u00f3n, es decir sue\u00f1os. \u00bfPero ustedes son capaces de so\u00f1ar?\u2026<br \/>\nY cuando el coraz\u00f3n est\u00e1 abierto y es capaz de so\u00f1ar hay lugar para la misericordia, hay lugar para acariciar a quienes sufren, hay lugar para ponerse al lado de quienes no tienen paz en el coraz\u00f3n o les falta lo necesario para vivir, o les falta la cosa m\u00e1s linda, la fe. Misericordia, digamos juntos esta palabra, Misericordia, otra vez.., otra vez para que el mundo sienta\u2026<br \/>\nTambi\u00e9n quiero confesarles otra cosa que aprend\u00ed en estos a\u00f1os. No quiero ofender a nadie. Me genera dolor encontrar a j\u00f3venes que parecen haberse \u00abjubilado\u00bb antes de tiempo. Esto me causa dolor, j\u00f3venes que parece se fueron en pensi\u00f3n a los 23, 24 o 25 a\u00f1os. Me genera dolor. Me preocupa ver a j\u00f3venes que \u00abtiraron la toalla\u00bb antes de empezar el partido. Que se han rendido sin haber comenzado a jugar. Me causa dolor ver a j\u00f3venes que caminan con rostros tristes, como si su vida no valiera. Son j\u00f3venes esencialmentes aburridos\u2026 y aburridores de los otros, y esto me causa dolor.<br \/>\nEs dif\u00edcil, y a su vez cuestionador, por otro lado, ver a j\u00f3venes que dejan la vida buscando el \u00abv\u00e9rtigo\u00bb, o de sensaci\u00f3n de sentirse vivos por caminos oscuros, que al final terminan \u00abpagando\u00bb\u2026y lo pagan caro. Piensen a muchos j\u00f3venes que ustedes conocen y eligieron este camino.  Hace pensar cuando se ve que hay j\u00f3venes que pierden hermosos a\u00f1os de su vida y sus energ\u00edas corriendo detr\u00e1s de vendedores de falsas ilusiones, y los hay \u00bfverdad? vendedores de falsas ilusiones. (En mi tierra natal dir\u00edamos \u00abvendedores de humo\u00bb), que les roban lo mejor de ustedes mismos, y esto me causa dolor. Estoy seguro que entre ustedes no los hay, pero quiero decirles que hay j\u00f3venes pensionados, que tiran la toalla antes del partido y los que entran con los v\u00e9rtigos de las falsas ilusiones y acaban en la nada.<br \/>\nPor eso, queridos amigos, nos hemos reunidos para ayudarnos mutuamente, porque no queremos dejarnos robar lo mejor de nosotros mismos, no queremos permitir que nos roben las energ\u00edas, la alegr\u00eda, los sue\u00f1os con falsas ilusiones.<br \/>\nQueridos amigos, les pregunto: \u00bfQui\u00e9ren para sus vidas ese v\u00e9rtigo alienante o quieren sentir esa fuerza que los haga sentirse vivos, plenos? \u00bfV\u00e9rtigo alienante o fuerza de la gracia?, qu\u00e9 quieren, \u00bfv\u00e9rtigo alienante o fuerza de plenitud?  No se escucha bien\u2026<br \/>\nPara ser plenos, para tener fuerza renovada, hay una respuesta, que no se vende, que no se compra, una respuesta que no es una cosa, que no es un objeto: es una persona y se llama Jesucristo. Un aplauso\u2026<br \/>\nMe pregunto, \u00bfJesucristo se puede comprar?\u2026  \u00bfSe vende en los negocios?\u2026  Jesucristo es un don, un regalo del Padre, el don de Nuestro Padre. Todos: Jesucristo es un don\u2026 Es un regalo del Padre\u2026<br \/>\nJesucristo es quien sabe darle verdadera pasi\u00f3n a la vida, Jesucristo es quien nos mueve a no conformarnos con poco y a dar lo mejor de nosotros mismos; es Jesucristo quien nos cuestiona, nos invita y nos ayuda a levantarnos cada vez que nos damos por vencidos. Es Jesucristo quien nos impulsa a levantar la mirada y a so\u00f1ar alto.<br \/>\nPero padre, alguien podr\u00e1 decirme que es tan dif\u00edcil y so\u00f1ar alto, que est\u00e1n dif\u00edcil estar siempre en subida. Padre soy d\u00e9bil, caigo, me esfuerzo pero acabo abajo. Los alpinos cuantos unen las monta\u00f1as cantan una canci\u00f3n hermosa que dice as\u00ed: en el arte de subir lo importante no es no caer, sino no quedarse ca\u00eddo. Si t\u00fa eres d\u00e9bil o caes, mira un poco hacia lo alto y est\u00e1 la mano tendida de Jes\u00fas que te dice lev\u00e1ntate y ven conmigo. Y si sucede otra vez, tambi\u00e9n. Y si sucede otra vez, tambi\u00e9n. Pedro una vez le pregunt\u00f3 al Se\u00f1or, \u00bfSe\u00f1or pero cuantas veces? y le dijo setenta veces siete. La mano de Jes\u00fas est\u00e1 siempre tendida para levantarnos cuando caemos. \u00bfLo han entendido?<br \/>\nEn el Evangelio hemos escuchado que Jes\u00fas, mientras se dirige a Jerusal\u00e9n, se detiene en una casa \u2013la de Marta, Mar\u00eda y L\u00e1zaro\u2013 que lo acoge. De camino, entra en su casa para estar con ellos; las dos mujeres reciben al que saben que es capaz de conmoverse. Las m\u00faltiples ocupaciones nos hacen ser como Marta: activos, distra\u00eddos, constantemente yendo de ac\u00e1 para all\u00e1\u2026; pero tambi\u00e9n solemos ser como Mar\u00eda: ante un buen paisaje, o un video que nos manda un amigo al m\u00f3vil, nos quedamos pensativos, en escucha.<br \/>\nEn estos d\u00edas de la JMJ, Jes\u00fas quiere entrar en nuestra casa; en tu casa, e mi casa. En el coraz\u00f3n de cada uno de nosotros. Quiere entrar y ver\u00e1 nuestras preocupaciones, en nuestro andar acelerado, como lo hizo con Marta\u2026 y esperar\u00e1 que lo escuchemos como Mar\u00eda; que, en medio del trajinar, nos animemos a entregarnos a \u00e9l. Que sean d\u00edas para Jes\u00fas, dedicados a escucharnos, a recibirlo en aquellos con quienes comparto la casa, la calle, el club o el colegio.<br \/>\nY quien acoge a Jes\u00fas, aprende a amar a Jes\u00fas. Entonces \u00e9l nos pregunta si queremos una vida plena y yo en su nombre les pregunto: \u00bfQuieren una vida plena?\u2026  Empieza desde ahora a dejarte conmover porque la felicidad germina y aflora en la misericordia: esa es su respuesta, esa es su invitaci\u00f3n, su desaf\u00edo, su aventura, la misericordia.<br \/>\nLa misericordia tiene siempre rostro joven; como el de Mar\u00eda de Betania sentada a los pies de Jes\u00fas como disc\u00edpula, que se complace en escucharlo porque sabe que ah\u00ed est\u00e1 la paz. Como el de Mar\u00eda de Nazareth, lanzada con su \u00abs\u00ed\u00bb a la aventura de la misericordia, y que ser\u00e1 llamada bienaventurada por todas las generaciones, llamada por todos nosotros \u00abla Madre de la Misericordia\u00bb.Invoqu\u00e9mosla todos juntos: Mar\u00eda Madre de misericordia. Todos: Mar\u00eda Madre de misericordia\u2026<br \/>\nAhora  cada uno repita en su coraz\u00f3n en silencio: Se\u00f1or, l\u00e1nzanos a la aventura de la misericordia. L\u00e1nzanos a la aventura de construir puentes y derribar muros, sean cercos o alambrados, l\u00e1nzanos a la aventura de socorrer al pobre, al que se siente solo y abandonado, al que ya no le encuentra sentido a su vida. L\u00e1nzanos a acompa\u00f1ar a aquellos que no te conocen y decirle lentamente y con tanto respeto t\u00fa nombre y el porqu\u00e9 de nuestra fe.<br \/>\nImp\u00falsanos a la escucha, como Mar\u00eda de Betania, de quienes no comprendemos, de los que vienen de otras culturas, de otros pueblos, incluso de aquellos a los que tememos porque creemos que pueden hacernos da\u00f1o. Haznos volver nuestra mirada, como Mar\u00eda de Nazareth con Isabel, a nuestros ancianos a nuestros abuelos para aprender de su sabidur\u00eda.<br \/>\nLes pregunto \u00bfustedes hablan con sus abuelos?, \u00bfas\u00ed as\u00ed?\u2026 Busquen a sus abuelos, ellos tienen sabidur\u00eda sobre la vida y les dir\u00e1n cosas que conmover\u00e1n vuestros corazones.<br \/>\nAqu\u00ed estamos, Se\u00f1or. Env\u00edanos a compartir tu Amor Misericordioso. Queremos recibirte en esta Jornada Mundial de la Juventud, queremos afirmar que la vida es plena cuando se la vive desde la misericordia, y que esa es la mejor parte, es la parte m\u00e1s dulce, y es la parte que nunca nos ser\u00e1 quitada. Am\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queridos j\u00f3venes, muy buenas tardes. Finalmente nos encontramos. Gracias por esta calurosa bienvenida. Gracias al Cardenal Dziwisz, a los Obispos, sacerdotes, religiosos y religiosas, seminaristas y a todos aquellos que los acompa\u00f1an. Gracias a los que han hecho posible que hoy estemos aqu\u00ed, que se la \u00abhan jugado\u00bb para que pudi\u00e9ramos celebrar la fe. O &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/francisco-a-los-jovenes-esperanza-de-un-mundo-nuevo\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1890","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=1890"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1890\/revisions"}],"predecessor-version":[{"id":1891,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/1890\/revisions\/1891"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=1890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=1890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=1890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}