{"id":328,"date":"2009-10-06T18:23:34","date_gmt":"2009-10-06T16:23:34","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=328"},"modified":"2009-10-06T18:23:34","modified_gmt":"2009-10-06T16:23:34","slug":"el-embargo-del-nino","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-embargo-del-nino\/","title":{"rendered":"El embargo del ni\u00f1o"},"content":{"rendered":"<p>Queridos Hermanos y amigos: Paz y Bien.<\/p>\n<p>Me ha conmovido la noticia ins\u00f3lita que han divulgado diversos informativos. Un ni\u00f1o, con sus once a\u00f1os casi infantiles a\u00fan, se apresura a llevar a una casa de embargos un peque\u00f1o mont\u00f3n de cosas suyas, que se dispone a empe\u00f1ar. Unos libros, unos discos, cuatro escasas cosas. \u00bfEstar\u00eda preparando alg\u00fan viaje con los compa\u00f1eros de curso?, \u00bfnecesitaba dinero para cambiar de m\u00f3vil?, \u00bfun capricho, tal vez, que se quer\u00eda subvencionar? Nada de eso.<\/p>\n<p>El chaval llegaba para sacar del apuro a su padre, que habiendo quedado en el paro, no encontrando trabajo por ning\u00fan sitio, ten\u00eda a toda la familia en una situaci\u00f3n l\u00edmite, desesperada, sin saber ya qu\u00e9 hacer ni por donde tirar. Y a este cr\u00edo, no se le ocurri\u00f3 m\u00e1s soluci\u00f3n que la de implicarse a s\u00ed mismo, poniendo en juego lo \u00fanico de lo que \u00e9l dispon\u00eda: su breve e infantil ajuar.<\/p>\n<p>Por m\u00e1s que sea tierna esta historia real, y verdaderamente conmovedora, tiene un transfondo muy duro, que es el que sucede a las personas reales. El transfondo es ese cuando en un hogar, en una familia, no entran desde hace tiempo los recursos necesarios para vivir, para sobrevivir, con serena dignidad y alegre esperanza. No se trata de las personas cuyos nombres an\u00f3nimos para nosotros leemos en los peri\u00f3dicos, sino que se trata tambi\u00e9n -y cada vez m\u00e1s- de las personas cercanas que conozco en mi barrio, en la escalera de mi casa, en la propia familia, en tu mismo hogar. Y es entonces cuando la noticia que nos relata el gesto de este peque\u00f1o, pierde su inocente ternura para empezar a percibirla como directa acusaci\u00f3n que nos hace pensar.<\/p>\n<p>\u00bfAcaso lo que en este mundo necesitamos los que en \u00e9l vivimos se ha evadido a otra galaxia? Parece ser que no, porque el mundo est\u00e1 bien hecho por Dios Creador. Pero \u00c9l nos ha dejado la libertad de administrar lo que se nos ha concedido con el don de la vida. Y es aqu\u00ed donde comienza la descripci\u00f3n de la tragedia de una crisis que siendo econ\u00f3mica tiene su origen en la tremenda crisis moral que estamos padeciendo: el ego\u00edsmo insolidario, la codicia insaciable, la usura aprovechona, el despilfarro materialista, la injusticia de guante blanco, la injusticia manchada de sangre, los intereses del poder dominante, el hedonismo fr\u00edvolo y embustero que promete lo que no dar\u00e1 jam\u00e1s, el relativismo atroz, la mentira como argumento, la utilizaci\u00f3n del hombre y la expulsi\u00f3n de Dios de nuestro para\u00edso terrenal.<\/p>\n<p>Hay una llamada a lo mejor (porque lo tienen) de nuestros pol\u00edticos y de nuestros distintos agentes sociales, para que dejen de calcular la crisis s\u00f3lo en clave de poder: sopesar las medidas necesarias a tomar contemplado no el bien de las personas sino \u00fanicamente el desgaste o el oportunismo electoral que tales medidas pueden contraer. Hay demasiadas personas sufriendo de veras, angustiadas por un horizonte negruzco, a las que debemos responder con las actitudes contrarias a las que nutren la crisis moral y provocan la crisis econ\u00f3mica.<\/p>\n<p>En nuestras comunidades cristianas, en particular desde cuanto se est\u00e1 haciendo en C\u00e1ritas y otras organizaciones eclesiales afines, miramos con asombro agradecido el ejemplo de un peque\u00f1o que dando lo que ten\u00eda se parece a aquel otro chaval que llev\u00f3 a Jes\u00fas tan s\u00f3lo dos peces y cinco panes, con los que el Se\u00f1or dio de comer hasta saciarse a una inmensa multitud. Este es el milagro que hace siempre Dios cuando ponemos en sus manos la aportaci\u00f3n sincera de nuestros bienes todos: los de la fe, los de la esperanza y los de la caridad.<\/p>\n<p>Recibid mi afecto y mi bendici\u00f3n.<br \/>\nJes\u00fas Montes Obispo de Huesca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queridos Hermanos y amigos: Paz y Bien. Me ha conmovido la noticia ins\u00f3lita que han divulgado diversos informativos. Un ni\u00f1o, con sus once a\u00f1os casi infantiles a\u00fan, se apresura a llevar a una casa de embargos un peque\u00f1o mont\u00f3n de cosas suyas, que se dispone a empe\u00f1ar. Unos libros, unos discos, cuatro escasas cosas. \u00bfEstar\u00eda &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-embargo-del-nino\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-328","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=328"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/328\/revisions"}],"predecessor-version":[{"id":366,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/328\/revisions\/366"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}