{"id":574,"date":"2010-01-19T18:25:52","date_gmt":"2010-01-19T16:25:52","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=574"},"modified":"2010-01-19T18:25:52","modified_gmt":"2010-01-19T16:25:52","slug":"un-testimonio-impresionante","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/un-testimonio-impresionante\/","title":{"rendered":"Un testimonio impresionante"},"content":{"rendered":"<p>TARJETA DE PRESENTACI\u00d3N <\/p>\n<p>      Hecho ocurrido en 1892, verdadero y parte de una biograf\u00eda <\/p>\n<p>Un se\u00f1or de unos 70 a\u00f1os viajaba en el tren, teniendo a su lado a un joven universitario que le\u00eda su libro de Ciencias. El caballero, a su vez, le\u00eda un libro de portada negra. Fue cuando el joven percibi\u00f3 que se trataba de la Biblia y que estaba abierta en el Evangelio de Marcos.<br \/>\n  Sin mucha ceremonia, el muchacho interrumpi\u00f3 la lectura del viejo y le pregunt\u00f3:<br \/>\n Se\u00f1or, \u00bfusted todav\u00eda cree en ese libro lleno de f\u00e1bulas y cuentos?<br \/>\n&#8211; S\u00ed, mas no es un libro de cuentos, es la Palabra de Dios.. \u00bfEstoy equivocado?<br \/>\n&#8211; Pero claro que lo est\u00e1. Creo que usted se\u00f1or deber\u00eda estudiar Historia Universal. Ver\u00eda que  la Revoluci\u00f3n Francesa, ocurrida hace m\u00e1s de 100 a\u00f1os, mostr\u00f3 la miop\u00eda de la religi\u00f3n.<br \/>\nSolamente personas sin cultura todav\u00eda creen que Dios hizo el mundo en 6 d\u00edas. Usted se\u00f1or deber\u00eda conocer un poco m\u00e1s lo que nuestros Cient\u00edficos dicen de todo eso.<br \/>\n&#8211; Y&#8230; \u00bfes eso mismo lo que nuestros cient\u00edficos dicen sobre la Biblia?<br \/>\n&#8211; Bien, como voy a bajar en la pr\u00f3xima estaci\u00f3n, no tengo tiempo de explicarle, pero d\u00e9jeme su tarjeta con su direcci\u00f3n para mandarle material cient\u00edfico por correo con la m\u00e1xima urgencia.<br \/>\nEl anciano entonces, con mucha paciencia, abri\u00f3 cuidadosamente el bolsillo derecho de su bolso y le dio su tarjeta al muchacho. Cuando \u00e9ste ley\u00f3 lo que all\u00ed dec\u00eda, sali\u00f3 cabizbajo, sinti\u00e9ndose peor que una hormiga.  En la tarjeta dec\u00eda:  <\/p>\n<p>Profesor Doctor Louis Pasteur<br \/>\nDirector General del Instituto de Investigaciones Cient\u00edficas<br \/>\nUniversidad Nacional de Francia<br \/>\n  &#8216;Un poco de Ciencia nos aparta de Dios.<br \/>\nMucha, nos aproxima&#8217;.<br \/>\n        Dr. Louis Pasteur<br \/>\nSaludos y abrazos  para todos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>TARJETA DE PRESENTACI\u00d3N Hecho ocurrido en 1892, verdadero y parte de una biograf\u00eda Un se\u00f1or de unos 70 a\u00f1os viajaba en el tren, teniendo a su lado a un joven universitario que le\u00eda su libro de Ciencias. El caballero, a su vez, le\u00eda un libro de portada negra. Fue cuando el joven percibi\u00f3 que se &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/un-testimonio-impresionante\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-574","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=574"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/574\/revisions"}],"predecessor-version":[{"id":575,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/574\/revisions\/575"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}