{"id":730,"date":"2010-05-18T22:27:11","date_gmt":"2010-05-18T20:27:11","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=730"},"modified":"2010-05-18T22:27:11","modified_gmt":"2010-05-18T20:27:11","slug":"vean-la-ultima-cima","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/vean-la-ultima-cima\/","title":{"rendered":"VEAN LA ULTIMA CIMA"},"content":{"rendered":"<p>VEAN LA ULTIMA CIMA ES UNA PELICULA ESCELENTE QUE NOS HARA MUCHO BIEN A TODA LA HUMANIDAD.<br \/>\nEstimado Jos\u00e9 Mar\u00eda,<br \/>\nQueremos invitarte a ver los 5 primeros minutos de la pel\u00edcula LA \u00daLTIMA CIMA, pinchando aqu\u00ed:<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/11835038\" width=\"1170\" height=\"658\" frameborder=\"0\" title=\"LA &Uacute;LTIMA CIMA - Inicio pel&iacute;cula\" webkitallowfullscreen mozallowfullscreen allowfullscreen><\/iframe><br \/>\nDesde ayer est\u00e1 activada la web oficial de LA \u00daLTIMA CIMA<br \/>\nhttp:\/\/www.laultimacima.com<br \/>\ndonde no s\u00f3lo puedes encontrar informaci\u00f3n amplia de la pel\u00edcula, sino donde tambi\u00e9n puedes dejar constancia de tu relaci\u00f3n personal con alg\u00fan sacerdote.<br \/>\nTambi\u00e9n pod\u00e9is solicitar en la web el estreno de LA \u00daLTIMA CIMA en vuestra ciudad. LA \u00daLTIMA CIMA SE ESTRENA POR ACLAMACI\u00d3N POPULAR \u00a1Es important\u00edsimo tu apoyo, para lograr que la pel\u00edcula vaya saltando de sala en sala, de ciudad en ciudad, de pa\u00eds en pa\u00eds!<br \/>\nDe momento, se estrena el 4 de junio en Madrid los Cines PALAFOX (C\/ Luchana, 15) y en los Cines DREAMS-Palacio de Hielo (C\/ Silvano,77), y estamos trabajando para que el 11 de junio, se estrene en Valencia, Bilbao, Sevilla.<br \/>\nQueremos agradecerte por los mensajes, cientos, que nos llegan para apoyar esta pel\u00edcula a la productora (Infinito M\u00e1s Uno) y a la distribuidora (European Dreams Factory). Este apoyo no es s\u00f3lo a la pel\u00edcula sino, tambi\u00e9n, un apoyo abierto y potente a los sacerdotes, por su servicio generoso. \u00a1\u00a1GRACIAS, QUERIDOS SACERDOTES!!<br \/>\nHasta ahora nos han pedido la pel\u00edcula desde M\u00e9xico, Colombia, Estados Unidos&#8230; Ojal\u00e1 llegue a todos los rincones del mundo.<br \/>\nMuchas gracias, de coraz\u00f3n, en mi nombre y en el de todo el equipo de LA \u00daLTIMA CIMA<br \/>\nRa\u00fal E. Recuero<br \/>\nInfinito M\u00e1s Uno<br \/>\nhttp:\/\/www.laultimacima.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VEAN LA ULTIMA CIMA ES UNA PELICULA ESCELENTE QUE NOS HARA MUCHO BIEN A TODA LA HUMANIDAD. Estimado Jos\u00e9 Mar\u00eda, Queremos invitarte a ver los 5 primeros minutos de la pel\u00edcula LA \u00daLTIMA CIMA, pinchando aqu\u00ed: Desde ayer est\u00e1 activada la web oficial de LA \u00daLTIMA CIMA http:\/\/www.laultimacima.com donde no s\u00f3lo puedes encontrar informaci\u00f3n amplia &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/vean-la-ultima-cima\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-730","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=730"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/730\/revisions"}],"predecessor-version":[{"id":731,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/730\/revisions\/731"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}