{"id":832,"date":"2010-08-17T18:38:03","date_gmt":"2010-08-17T16:38:03","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=832"},"modified":"2010-08-17T18:38:03","modified_gmt":"2010-08-17T16:38:03","slug":"el-ecumenismo-de-la-santidad","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-ecumenismo-de-la-santidad\/","title":{"rendered":"El Ecumenismo de la Santidad&#8230;"},"content":{"rendered":"<p><strong>El Papa propone el \u201cecumenismo de la santidad\u201d del Hermano Roger<\/strong>En el 70 aniversario de la fundaci\u00f3n de Taiz\u00e9 y el 5\u00ba de la muerte de su fundador<br \/>\nTAIZ\u00c9, lunes 16 de agosto de 2010 (ZENIT.org).- Benedicto XVI ha auspiciado que el testimonio del fundador de Taiz\u00e9, el Hermano Roger, \u201cde un ecumenismo de la santidad nos inspire en nuestro camino hacia la unidad\u201d.<\/p>\n<p>Lo puso de relieve en un mensaje enviado al actual prior de la comunidad de Taiz\u00e9, el Hermano Alois, con motivo del doble aniversario de los 70 a\u00f1os de la fundaci\u00f3n de la comunidad de Taiz\u00e9 y los 5 a\u00f1os de la muerte de su fundador, el Hermano Roger.<\/p>\n<p>Unas cinco mil personas celebraron esta doble conmemoraci\u00f3n en Taiz\u00e9 el pasado 14 de agosto, con el ingreso de un nuevo hermano en la comunidad, una oraci\u00f3n y una peregrinaci\u00f3n, inform\u00f3 la comunidad de Taiz\u00e9.<\/p>\n<p>El acto empez\u00f3 a las siete y media de la tarde en un gran campo al lado del pueblo franc\u00e9s de Taiz\u00e9, con la celebraci\u00f3n, al aire libre, de la oraci\u00f3n com\u00fan.<\/p>\n<p>Un joven italiano que hab\u00eda entrado hace un tiempo en la comunidad tom\u00f3 el h\u00e1bito blanco de los hermanos de esta comunidad ecum\u00e9nica.<\/p>\n<p>La oraci\u00f3n fue enriquecida con cantos, un texto b\u00edblico le\u00eddo en varios idiomas por j\u00f3venes de diversos continentes y un momento de silencio.<\/p>\n<p>A continuaci\u00f3n, los hermanos y los miles de j\u00f3venes de setenta pa\u00edses que acababan de pasar una semana en Taiz\u00e9, as\u00ed como algunos ni\u00f1os, atravesaron el peque\u00f1o pueblo de Taiz\u00e9 en peregrinaci\u00f3n.<\/p>\n<p>Pasaron por delante del cementerio de la peque\u00f1a iglesia rom\u00e1nica donde descansan los restos del Hermano Roger y donde fue colocado, para la ocasi\u00f3n, el icono egipcio de la amistad, que era muy querido por el fundador de la comunidad. <\/p>\n<p>Y se dirigieron a la iglesia de la Reconciliaci\u00f3n, donde se ley\u00f3 el Evangelio de la resurrecci\u00f3n y los asistentes iluminaron miles de peque\u00f1as velas como s\u00edmbolo de la esperanza en la resurrecci\u00f3n. <\/p>\n<p>El Hermano Alois pronunci\u00f3 las \u00fanicas palabras del acto, una oraci\u00f3n en la que dio gracias a Dios \u201cpor la vida entregada de nuestro hermano Roger que nos ha dejado hace ya 5 a\u00f1os, y que hace 70 a\u00f1os lleg\u00f3 solo a este pueblecito de Taiz\u00e9\u201d.<\/p>\n<p>La oraci\u00f3n record\u00f3 algunos aspectos del fundador de Taiz\u00e9: \u201cBuscaba vivir ardientemente de tu confianza y decir tu bondad infinita por cada ser humano\u201d.<\/p>\n<p>\u201cEn esa confianza, t\u00fa le concediste encontrar la fuente de la alegr\u00eda y de la paz: la paz del coraz\u00f3n, que fue lo que hizo de \u00e9l un creador de paz entre los hombres\u201d, continu\u00f3 el prior. <\/p>\n<p>\u201cComo San Juan Bautista, tan solo quer\u00eda preparar los caminos de Cristo y reunir a tu pueblo para decirle a todos que &#8216;Dios est\u00e1 muy cerca de vosotros&#8217;\u201d, a\u00f1adi\u00f3. <\/p>\n<p>Entre otras cosas, record\u00f3 que el Hermano Roger, \u201caunque pobre y vulnerable, usando sus propias expresiones, con todas sus fuerzas eligi\u00f3 amar\u201d. <\/p>\n<p>\u201cAmaba a tu Iglesia, que re\u00fane a los creyentes en un \u00fanica comuni\u00f3n m\u00e1s all\u00e1 de todas las fronteras pol\u00edticas, sociales o culturales -afirm\u00f3-. \u00c9sta era para \u00e9l el signo de esperanza de una humanidad reconciliada\u201d. <\/p>\n<p>Con motivo del aniversario, numerosas personalidades enviaron mensajes a la comunidad de Taiz\u00e9, entre ellas el Papa Benedicto XVI, los patriarcas de Constantinopla y de Mosc\u00fa, el arzobispo de Canterbury y los responsables luteranos y reformados. <\/p>\n<p>Mensaje del Papa <\/p>\n<p>En su mensaje, el Pont\u00edfice manifiesta \u201csu cercan\u00eda espiritual y su uni\u00f3n en la oraci\u00f3n con la comunidad y con todos aquellos que participan en la conmemoraci\u00f3n del recuerdo del Hermano Roger\u201d. <\/p>\n<p>Benedicto XVI se refiere al fundador de Taiz\u00e9 como a un \u201ctestigo incansable del Evangelio de paz y de reconciliaci\u00f3n\u201d y como a \u201cun pionero en el dif\u00edcil camino hacia la unidad entre los disc\u00edpulos de Cristo\u201d. <\/p>\n<p>\u201cHace setenta a\u00f1os dio inicio a una comunidad que sigue viendo c\u00f3mo acuden a ella miles de j\u00f3venes provenientes de todo el mundo, buscando dar un sentido a su vida, los acoge en la oraci\u00f3n y les permite experimentar una relaci\u00f3n personal con Dios\u201d, constata el Papa en su mensaje, firmado por el secretario de Estado vaticano, el cardenal Tarcisio Bertone. <\/p>\n<p>\u201cAhora que ha entrado en la alegr\u00eda eterna, sigue habl\u00e1ndonos -a\u00f1ade-. Que su testimonio de un ecumenismo de la santidad nos inspire en nuestro camino hacia la unidad y que vuestra Comunidad siga viviendo e irradiando su carisma, especialmente entre las generaciones j\u00f3venes. <\/p>\n<p>Para la doble conmemoraci\u00f3n que est\u00e1 celebrando Taiz\u00e9, se ha publicado el libro Vivir para amar, dirigido especialmente a j\u00f3venes, que contiene algunos textos esenciales del Hermano Roger. <\/p>\n<p>En el prefacio del librito, el Hermano Alois afirma que la herencia que ha dejado el Hermano Roger \u201cest\u00e1 viva\u201d. <\/p>\n<p>\u201c\u00c9l ten\u00eda la certeza de que Dios est\u00e1 unido a cada ser humano, incluso a quienes no tienen conciencia de ello\u201d, destaca. <\/p>\n<p>Y a\u00f1ade que \u201ca partir de esta confianza en la presencia de Dios\u201d, el fundador de Taiz\u00e9 \u201cencontraba una paz que intentaba comunicar a los dem\u00e1s\u201d. <\/p>\n<p>Roger Schutz lleg\u00f3 a Taiz\u00e9 en agosto de 1940 en plena Segunda Guerra Mundial, procedente de Suiza. <\/p>\n<p>Se estableci\u00f3 en este peque\u00f1o pueblo franc\u00e9s cercano a Cluny y empez\u00f3 a acoger a refugiados, especialmente jud\u00edos. <\/p>\n<p>As\u00ed empez\u00f3 la comunidad de Taiz\u00e9, convertida hoy en un centro de espiritualidad internacional y ecum\u00e9nico que atrae a centenares de miles de personas, sobre todo j\u00f3venes, de toda confesi\u00f3n religiosa y punto de referencia para el di\u00e1logo y el ecumenismo. <\/p>\n<p>El Hermano Roger falleci\u00f3 el 16 de agosto de 2005, asesinado por una mujer desequilibrada durante la oraci\u00f3n vespertina en la iglesia de la Reconciliaci\u00f3n de Taiz\u00e9. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Papa propone el \u201cecumenismo de la santidad\u201d del Hermano RogerEn el 70 aniversario de la fundaci\u00f3n de Taiz\u00e9 y el 5\u00ba de la muerte de su fundador TAIZ\u00c9, lunes 16 de agosto de 2010 (ZENIT.org).- Benedicto XVI ha auspiciado que el testimonio del fundador de Taiz\u00e9, el Hermano Roger, \u201cde un ecumenismo de la &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/el-ecumenismo-de-la-santidad\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-832","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=832"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/832\/revisions"}],"predecessor-version":[{"id":833,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/832\/revisions\/833"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}