{"id":878,"date":"2011-01-31T10:51:26","date_gmt":"2011-01-31T08:51:26","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=878"},"modified":"2011-01-31T12:42:29","modified_gmt":"2011-01-31T10:42:29","slug":"nao-xii-solo-tu-mi-fuente-marzo-2011","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/nao-xii-solo-tu-mi-fuente-marzo-2011\/","title":{"rendered":"Nao XII &#8211; \u00abS\u00f3lo t\u00fa, mi fuente\u00bb (marzo 2011)"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.salvatorianos.org\/espana\/docs\/actividades\/2010\/nao2010_1.jpg\" alt=\"\" \/><\/p>\n<h2>NAO XII<\/h2>\n<h3>\u201cSOLO T\u00da,<br \/>\nMI FUENTE\u201d<\/h3>\n<p>(firmado: la nao)<\/p>\n<p>\u201cQuien tenga sed acuda a m\u00ed a beber, el que tenga fe en m\u00ed, como dice la Escritura: de sus entra\u00f1as manar\u00e1n r\u00edos de agua viva\u201d (Jn7,37-38)<\/p>\n<p>\u201c\u2026 el agua que yo le d\u00e9 se convertir\u00e1 dentro de \u00e9l en fuente de agua que brota dando vida eterna\u201d (Jn 4,14)<\/p>\n<p>\u201cDesde tu fuente quiero beber, quiero vivir y fuente ser por ser de ti. Quitar de m\u00ed cualquier pensar que al fin distraiga mi fe en ti y en tu Palabra. Fuente en ti, fuente por ti, s\u00f3lo t\u00fa, mi fuente.\u201d (Canto)<\/p>\n<p>Queridos navegantes<\/p>\n<p>Como cada curso por este tiempo os recordamos la fecha de la pr\u00f3xima nao, para que la teng\u00e1is en cuenta en vuestras programaciones anuales. La nao XII la celebraremos  el fin de semana <strong>4, 5 y 6 de marzo de 2011. <\/strong><\/p>\n<p>El lema de este a\u00f1o <strong><em>\u201cS\u00f3lo T\u00fa, mi Fuente\u201d<\/em><\/strong> nos invita a ir a las fuentes, a los or\u00edgenes, al principio, a la ra\u00edz, al fundamento, a lo esencial, a lo aut\u00e9ntico\u2026., a ver en qu\u00e9 fuentes saciamos nuestra sed y a cuestionar todo lo que hacemos en su nombre desde donde y porqu\u00e9 lo hacemos. \u00bfEres s\u00f3lo t\u00fa mi fuente?, \u00bfes tu Evangelio, de locura, fraternidad y justicia, la raz\u00f3n \u00fanica de mi vivir?, \u00bfes verdad que solo desde tu fuente quiero beber, quiero vivir y fuente ser?<\/p>\n<p>Os deseamos de coraz\u00f3n lo mejor para este curso: \u201cbeber del agua viva\u201d para que todos nuestros proyectos nazcan y las realices T\u00fa, para el bien de todos, en especial de los m\u00e1s peque\u00f1os, abandonados y empobrecidos.<\/p>\n<p><em><br \/>\nUn fuerte abrazo ilusionado<\/em><\/p>\n<p><em>de parte de todos los tripulantes de la nao<br \/>\n<\/em><br \/>\n<!--more--><br \/>\n<strong>NAO XII<\/strong>:<br \/>\nEl fin de semana   4, 5 y 6 de  marzo de 2011 en Madrid<\/p>\n<p>a) Retiro nao: del 1 al viernes 4 de marzo<\/p>\n<p>b) Talleres, foros, mesa redonda y concierto por la unidad: ma\u00f1ana y tarde del s\u00e1bado 5 de marzo<\/p>\n<p>c) Vigila de Oraci\u00f3n: desde las 22,15 h del s\u00e1bado 5 de marzo.<\/p>\n<p>LUGAR: el mismo de los \u00faltimos a\u00f1os.<\/p>\n<p>Contacto: <a href=\"mailto:nao@todosuno.org\">nao@todosuno.org<\/a> 913682629; 665311501;<\/p>\n<p><strong>La NAO: <\/strong><br \/>\n<em> <\/em><\/p>\n<p><em>\u201c\u00bfAlgo m\u00e1s que Arte?,<\/em><\/p>\n<p><em>\u00bfAlgo m\u00e1s que Oraci\u00f3n?,<\/em><\/p>\n<p><em>\u00bfAlgo m\u00e1s que una noche?:<\/em><\/p>\n<p><em>Un estado permanente del alma que, desde lo desapercibido,<\/em><\/p>\n<p><em>busca ser <strong>de todos y para todos<\/strong>.\u201d<\/em><\/p>\n<p><em> <\/em><\/p>\n<p><span style=\"text-decoration: underline;\">Canto (Brotes Olivo)<\/span>: <strong>Solo T\u00fa, mi fuente<\/strong> Sal 119 (118) &#8211; Jn 7,37-38<\/p>\n<p>Desde tu fuente quiero beber,<\/p>\n<p>quiero vivir y fuente ser por ser de ti.<\/p>\n<p>Quitar de m\u00ed cualquier pensar<\/p>\n<p>que al fin distraiga mi fe en ti y en tu Palabra.<\/p>\n<p><strong>Fuente en ti, fuente por ti, s\u00f3lo t\u00fa, mi fuente.<\/strong><\/p>\n<p>Lo hiciste todo pensando en m\u00ed,<\/p>\n<p>instando a ser lo que he de ser: vivir por ti.<\/p>\n<p>Sintiendo en mi alma que tu ser Dios<\/p>\n<p>Habita en mi y aunque no quiera soy tu Palabra.<\/p>\n<p>T\u00fa me has pedido manifestar<\/p>\n<p>a todo hombre que somos t\u00fa en la unidad.<\/p>\n<p>Y as\u00ed, al vivir esta conciencia,<\/p>\n<p>seremos juntos el Dios del cielo, aqu\u00ed en la tierra<\/p>\n<p><a href=\"http:\/\/www.brotesdeolivo.es\/index.php?option=com_content&amp;task=blogcategory&amp;id=40&amp;Itemid=42\" target=\"_blank\">http:\/\/www.brotesdeolivo.es\/index.php?option=com_content&amp;task=blogcategory&amp;id=40&amp;Itemid=42<\/a> (para escuchar la canci\u00f3n)<\/p>\n<p><a href=\"http:\/\/www.brotesdeolivo.es\/index.php?option=com_docman&amp;task=cat_view&amp;gid=38&amp;Itemid=14\" target=\"_blank\">http:\/\/www.brotesdeolivo.es\/index.php?option=com_docman&amp;task=cat_view&amp;gid=38&amp;Itemid=14<\/a> (para descargar la canci\u00f3n)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAO XII \u201cSOLO T\u00da, MI FUENTE\u201d (firmado: la nao) \u201cQuien tenga sed acuda a m\u00ed a beber, el que tenga fe en m\u00ed, como dice la Escritura: de sus entra\u00f1as manar\u00e1n r\u00edos de agua viva\u201d (Jn7,37-38) \u201c\u2026 el agua que yo le d\u00e9 se convertir\u00e1 dentro de \u00e9l en fuente de agua que brota dando &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/nao-xii-solo-tu-mi-fuente-marzo-2011\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-878","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=878"}],"version-history":[{"count":7,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/878\/revisions"}],"predecessor-version":[{"id":974,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/878\/revisions\/974"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}