{"id":933,"date":"2010-12-23T06:20:22","date_gmt":"2010-12-23T04:20:22","guid":{"rendered":"http:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/?p=933"},"modified":"2010-12-23T06:20:22","modified_gmt":"2010-12-23T04:20:22","slug":"y-algunos-preguntaron","status":"publish","type":"post","link":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/y-algunos-preguntaron\/","title":{"rendered":"Y algunos preguntaron&#8230;."},"content":{"rendered":"<p><strong>Y algunos preguntaron:<\/strong>\u201c\u00bfEres t\u00fa el que ha de venir o esperamos a otro?\u201d<br \/>\nY el les dijo simplemente:<br \/>\n\u201cMirad a vuestro alrededor:<br \/>\n&#8211; hay gente que no sab\u00eda ver y ahora han aprendido<br \/>\na mirar<br \/>\n&#8211; hay gente que no pod\u00edan caminar -vinieron<br \/>\nCojeando de otras tierras- y ahora caminan seguros por<br \/>\nNuestras calles.<br \/>\n&#8211; hay gente que repel\u00eda a los dem\u00e1s -miseria, sexo, raza, cultura- y ahora se sienten personas dignas.<br \/>\n&#8211; hay gente que no quer\u00eda o\u00edr los gritos de los<br \/>\nDesfallecidos, y por fin han abierto sus o\u00eddos y se inclinan sobre las heridas de los m\u00e1s d\u00e9biles.<br \/>\n&#8211; hay gente cuya vida era muerte, y han resucitado<br \/>\na la solidaridad. Se han quitado de encima mucho peso que les sobraba. Se afanan por encontrar salidas a los que no las tienen.<\/p>\n<p>&#8211; hay mucha gente que anuncia la esperanza a los<br \/>\ndesesperanzados. Y son Buena Noticia del Dios de los pobres.<br \/>\n\u00a1Dichosos los que no se escandalizan de la paz y la Justicia.<br \/>\nY esto es lo que nos ha traido desde lo alto el Buen Dios y lo que tenemos que sembrar los que queremos seguirle a El.<br \/>\nChema sds.<\/p>\n<p>Donde se atropella la dignidad y los derechos de la persona humana; donde los ego\u00edsmos personales o de grupo prevalecen sobre el bien com\u00fan; donde se corre el riesgo de habituarse al odio fratricida y a la explotaci\u00f3n del hombre por el hombre; donde las luchas intestinas dividen grupos y etnias y laceran la convivencia; donde el terrorismo sigue golpeando; donde falta lo necesario para vivir; donde se mira con desconfianza un futuro que se est\u00e1 haciendo cada vez m\u00e1s incierto, incluso en las naciones del bienestar: que en todos estos casos brille la Luz de la Navidad y anime a todos a hacer su propia parte, con esp\u00edritu de aut\u00e9ntica solidaridad. <\/p>\n<p>(Mensaje de Navidad del Santo Padre Benedicto XVI, pronunciado en la ma\u00f1ana del 25 de diciembre de 2009)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y algunos preguntaron:\u201c\u00bfEres t\u00fa el que ha de venir o esperamos a otro?\u201d Y el les dijo simplemente: \u201cMirad a vuestro alrededor: &#8211; hay gente que no sab\u00eda ver y ahora han aprendido a mirar &#8211; hay gente que no pod\u00edan caminar -vinieron Cojeando de otras tierras- y ahora caminan seguros por Nuestras calles. &#8211; &bull;  <a class=\"read-more\" href=\"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/y-algunos-preguntaron\/\"> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-933","post","type-post","status-publish","format-standard","hentry","category-buenas-noticias"],"_links":{"self":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/comments?post=933"}],"version-history":[{"count":1,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/933\/revisions"}],"predecessor-version":[{"id":934,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/posts\/933\/revisions\/934"}],"wp:attachment":[{"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/media?parent=933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/categories?post=933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvatorianos.org\/blog\/familiasalvatoriana\/wp-json\/wp\/v2\/tags?post=933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}